{"id":3709,"date":"2020-08-25T14:00:00","date_gmt":"2020-08-25T13:00:00","guid":{"rendered":"https:\/\/www.jimdo.com/de/magazin\/?p=3709"},"modified":"2023-08-03T09:51:08","modified_gmt":"2023-08-03T08:51:08","slug":"individuelle-verpackung","status":"publish","type":"post","link":"https:\/\/www.jimdo.com/de/magazin\/individuelle-verpackung\/","title":{"rendered":"Echt praktisch \u2013 So findet ihr top Verpackungsideen f\u00fcr den Onlineshop"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Klicken eure Kunden auf \u201cKaufen\u201d, hat ihre Bestellung noch eine lange Reise vor sich. Dabei wird euer Paket wom\u00f6glich ordentlich durchgesch\u00fcttelt, f\u00e4llt zu Boden oder dient als Ablage f\u00fcr ein noch schwereres Paket.&nbsp;Eine widerstandsf\u00e4hige Verpackung ist daher ein absolutes Muss.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Doch eine Verpackung ist mehr als nur eine Schutzh\u00fclle f\u00fcr euer Produkt. Sie repr\u00e4sentiert auch euch und eure Marke. Von exklusiv und luxuri\u00f6s zu bis zu umweltfreundlich und nachhaltig \u2013 was sagt eure Verpackung \u00fcber euch aus?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In diesem Artikel behandeln wir mehrere Methoden, wie ihr eure Waren sicher verpackt. Und wie ihr Produktverpackungen entwerft, die zu eurer Marke passen. Wagen wir also gemeinsam einen Blick \u00fcber den Teller- bzw. Pappschachtelrand hinaus, um euren Kunden ein einmaliges Verpackungserlebnis zu bieten.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-flat ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.jimdo.com/de/magazin\/individuelle-verpackung\/#1_So_waehlt_ihr_die_richtige_Produktverpackung\" >1. So w\u00e4hlt ihr die richtige Produktverpackung<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.jimdo.com/de/magazin\/individuelle-verpackung\/#2_So_entwerft_ihr_Produktverpackungen_die_euch_von_der_Konkurrenz_abheben\" >2. So entwerft ihr Produktverpackungen, die euch von der Konkurrenz abheben<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.jimdo.com/de/magazin\/individuelle-verpackung\/#3_Wie_ihr_euren_Kunden_das_beste_Auspack-Erlebnis_bereitet\" >3. Wie ihr euren Kunden das beste Auspack-Erlebnis bereitet<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.jimdo.com/de/magazin\/individuelle-verpackung\/#Eure_Verpackung_kann_mehr\" >Eure Verpackung kann mehr<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"1_So_waehlt_ihr_die_richtige_Produktverpackung\"><\/span>1. So w\u00e4hlt ihr die richtige Produktverpackung<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Das Wichtigste, was eine Verpackung leisten muss: Sie muss eure Waren sch\u00fctzen. Kommt sie besch\u00e4digt an, sind eure Kunden mehr als entt\u00e4uscht und <a href=\"https:\/\/www.jimdo.com/de/magazin\/retouren-reduzieren-onlineshop\/\">eure Retouren<\/a> werden in die H\u00f6he schnellen. Daher empfiehlt sich widerstandsf\u00e4higes und wasserdichtes Material au\u00dfen und weiches F\u00fcllmaterial im Inneren des Pakets. Doch \u00fcbertreibt es nicht mit eurer Verpackung! Ihr wollt schlie\u00dflich nicht, dass das Auspacken eure Kunden frustet!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Legt daher mit folgenden \u00dcberlegungen los:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Bestellt Verpackungsproben.<\/strong> Standard-Verpackungsmaterialien, die ihr mit eigenen Designs bedrucken k\u00f6nnt, sind vor allem f\u00fcr kleinere Unternehmen eine gute L\u00f6sung. Doch bevor ihr euch f\u00fcr einen Anbieter entscheidet, solltet ihr zuerst eine kleine Menge als Test bestellen. So findet ihr heraus, wo Preis und Leistung stimmen.<\/li>\n\n\n\n<li><strong>\u00dcberlegt euch Alternativen zu Paketen.<\/strong> Gepolsterte Umschl\u00e4ge oder Versandt\u00fcten eigenen sich vor allem f\u00fcr kleinere Produkte und Kleidung. Da diese Verpackungen so leicht sind, haltet ihr damit eure Versandkosten niedrig. Ebenso sind sie perfekt f\u00fcr <a href=\"https:\/\/www.jimdo.com/de/magazin\/versandarten-onlineshop\/\">lokale Versandarten<\/a>. Etwa f\u00fcr Zustellungen zu Fu\u00df oder mit dem Fahrrad.<\/li>\n\n\n\n<li><strong>Verwendet 3 oder 4 verschiedene Gr\u00f6\u00dfen.<\/strong> Auf diese Weise seid ihr f\u00fcr die meisten Bestellungen eurer Kunden ger\u00fcstet. Kauft ein Kunde drei B\u00fccher bei euch, wollt ihr sie schlie\u00dflich nicht alle einzeln verschicken. Ebenso ver\u00e4rgert ihr eure Kunden nicht damit, dass ihr ein einzelnes Paar Ohrringe in einer unn\u00f6tig gro\u00dfe Schachtel verkauft. Auch k\u00f6nnt ihr euch so von <a href=\"https:\/\/www.jimdo.com/de/magazin\/lokale-unternehmen-mit-amazon-mithalten\/\">gro\u00dfen H\u00e4ndlern wie Amazon abheben<\/a>.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><div class=\"jimdo-alert\">\u00dcberlegt euch, wiederverwendbare Verpackung zu verwenden. Mehrere Versandh\u00e4ndler wie Otto oder Zalando experimentieren zum Beispiel gerade mit einer L\u00f6sung namens <a href=\"https:\/\/www.originalrepack.com\/?lang=de\">RePack<\/a>.<\/div><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Testet eure Verpackung<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Eine gute Verpackung l\u00e4sst sich leicht \u00f6ffnen, ohne dass ihr dabei die Ware besch\u00e4digt. Deshalb haben wir hier ein paar Tipps f\u00fcr euch, wie ihr eure Verpackung auf Herz und Nieren testen k\u00f6nnt:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Versucht, eure Verpackung selbst zu \u00f6ffnen. <\/strong>Packt eure Ware so ein, als w\u00fcrdet ihr sie verschicken wollen. Nun versucht, alles nur mit den H\u00e4nden wieder auszupacken. Klappt das? Oder m\u00fcsst ihr eine Schere zu Hilfe nehmen? Und wie sieht es mit Freunden und Familie aus? Bekommen die es hin? Sagt ihnen ruhig, dass sie nicht allzu zimperlich sein sollen. Eure Kunden sind es wahrscheinlich auch nicht.<\/li>\n\n\n\n<li><strong>Lasst eure Verpackung zu Boden fallen \u2013 und stellt sie dann unter die Dusche.<\/strong> So seht ihr, wie stabil und wasserdicht eure Verpackung tats\u00e4chlich ist. Falls n\u00f6tig k\u00f6nnt ihr zus\u00e4tzliches F\u00fcllmaterial verwenden oder eine zus\u00e4tzliche Schicht aus wasserdichtem Material hinzuf\u00fcgen.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Was ist bei euren Tests schiefgelaufen? Je nachdem lohnt es sich, eure Verpackung nochmals zu \u00fcberarbeiten oder eine Anleitung zum \u00d6ffnen auf der Au\u00dfenseite anzubringen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2_So_entwerft_ihr_Produktverpackungen_die_euch_von_der_Konkurrenz_abheben\"><\/span>2. So entwerft ihr Produktverpackungen, die euch von der Konkurrenz abheben<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Viele Kunden warten sehns\u00fcchtig darauf, dass ihre Bestellung endlich ankommt. Sehen sie euer Logo und euren Namen auf einem Paket, ist das ihr erster gro\u00dfer Moment der Freude: \u201cJuhuuuu!! Mein Paket ist da!\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine Verpackung mit eurem Logo darauf hat noch weitere Vorteile: Schon beim Transport kann jeder eure Marke sehen. Auch wenn eure Kunden eure Verpackung wiederverwenden, um selbst etwas zu verschicken. Kunden, die eines eurer Pakete bei einem Freund sehen, werden es sofort wiedererkennen. Und das st\u00e4rkt ihre Bindung zu eurem Shop.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zudem gibt es Studien aus dem Bereich Neuromarketing, die darauf hinweisen, dass <a href=\"https:\/\/www.neuromarketing-wissen.de\/artikel\/verpackung\">verschiedene Verpackungsdesigns unterschiedliche Emotionsfelder im Gehirn stimulieren<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">W\u00e4hlt die richtigen Farben<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">2019 wurden in Deutschland 3,65 Mrd. Kurier-, Express- und Paketsendungen verschickt. Wie viele davon in Standard-Gelb oder -Braun, k\u00f6nnen wir nicht sagen, doch bestimmt war es der Gro\u00dfteil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indem ihr euer eigenes kreatives Design verwendet, hebt ihr euch von der Masse ab. Und falls ihr euch doch f\u00fcr ein Standardpaket entscheidet, k\u00f6nnt ihr zumindest noch eine bestimmte Farbe oder ein spezielles Muster w\u00e4hlen. Der niederl\u00e4ndische H\u00e4ndler HEMA macht das seit Jahren. Seine rot gepunkteten Pakete kennt jeder. Meistens besteht ein <a href=\"https:\/\/youtu.be\/5PFhKuc3QOs?t=4\">Teil der Schachtel aus einer Bastelvorlage<\/a>, die ihr selbst ausschneiden und zusammenbauen k\u00f6nnt. Dieser clevere Verpackungstrick sorgt daf\u00fcr, dass ihr im Gespr\u00e4ch bleibt und gibt den kleinen (und gro\u00dfen) Kindern eurer Kunden etwas zu tun.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><div class=\"jimdo-alert\">Seht euch alle Teile eurer Verpackung an, auch das Versandetikett und das Paketband. Selbst die k\u00f6nnt ihr selbst gestalten! Zum Beispiel Klebeband in euren Shop-Farben oder mit eurem <a href=\"https:\/\/www.jimdo.com/de/magazin\/logo-design\/\">Logo<\/a>.<\/div><\/p>\n\n\n\n\n\n<h3 class=\"wp-block-heading\">W\u00e4hlt den passenden Aufdruck<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Euer Logo und euer <a href=\"https:\/\/www.jimdo.com/de/magazin\/firmenname-unternehmensname-finden\/\">Unternehmensname<\/a> sollten unbedingt auf eure Verpackung. Eure Social-Media-Profile sind ebenfalls eine gute Idee. So erinnert ihr Kunden daran, euch zu folgen und auf ihren eigen Profilen zu posten, was sie so toll an eurem Produkt finden. Wer wei\u00df, einige werden vielleicht sogar ein <a href=\"https:\/\/business.trustedshops.de\/blog\/unboxing-e-commerce\/\">Unboxing Video<\/a> aufnehmen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein weiteres gutes Beispiel aus der Praxis kommt vom E-Bike-H\u00e4ndler Van Moof. W\u00e4hrend der Zustellung fielen die schweren Pakete oft herunter, die R\u00e4der wurden besch\u00e4digt und die Kunden mussten sie wieder zur\u00fcckschicken. Das hei\u00dft, Van Moof musste die Kosten f\u00fcr das besch\u00e4digte Produkt sowie f\u00fcr die <a href=\"https:\/\/www.jimdo.com/de/magazin\/retouren-reduzieren-onlineshop\/\">Retoure<\/a> tragen. Und obendrein hatten ihre Kunden auch ein schlechtes Einkaufserlebnis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die L\u00f6sung: Van Moof druckt nun das Bild eines Fernsehers au\u00dfen auf die Schachtel. Dadurch werden die Paketboten automatisch vorsichtiger, da sie genau wissen, wie empfindlich ein moderner Flat-Screen-Fernseher ist. <a href=\"https:\/\/www.sueddeutsche.de\/panorama\/fahrrad-fernseher-usa-1.4318821\">So gingen die Reklamationen um ganze 80 Prozent zur\u00fcck<\/a>!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Entscheidet euch f\u00fcr eine nachhaltige Verpackung<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Wiederverwendbare Au\u00dfenverpackung haben wir bereits erw\u00e4hnt. Doch auch das Innere eurer Schachtel kann nachhaltig sein. Wollt ihr beispielsweise eine zus\u00e4tzliche Schutzschicht zwischen verschiedenen Produkten einziehen, k\u00f6nnt ihr Samenpapier verwenden. Das besteht aus zwei Lagen Papier mit Pflanzensamen dazwischen. Nach dem Auspacken k\u00f6nnen eure Kunden aus dem Packpapier Blumen, Kr\u00e4uter oder Gem\u00fcse z\u00fcchten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Kosmetikhersteller Lush ist ein wahrer Meister in dieser Disziplin. Anstatt Styropor als F\u00fcllmaterial verwendet das Unternehmen EcoFlo was zu 100 Prozent aus Mais- und Kartoffelst\u00e4rke besteht. Auf der <a href=\"https:\/\/de.lush.com\/help\/faqs\/orders\/woraus-besteht-das-fuellmaterial-meinem-lush-paket\">offiziellen Seite<\/a> hei\u00dft es: \u201cDu kannst es in Wasser aufl\u00f6sen, in der Erde verbuddeln oder wiederverwenden, je nachdem, wonach dir der Sinn steht.\u201d Dieser Service passt perfekt zu den Werten und der <a href=\"https:\/\/www.jimdo.com\/de\/magazin\/markentonalitaet-kundenansprache\/\">Tonalit\u00e4t ihrer Marke<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3_Wie_ihr_euren_Kunden_das_beste_Auspack-Erlebnis_bereitet\"><\/span>3. Wie ihr euren Kunden das beste Auspack-Erlebnis bereitet<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bei einer ganz gew\u00f6hnlichen Verpackung beschr\u00e4nkt sich die Aufmerksamkeit eures Kunden ausschlie\u00dflich auf seine Bestellung. Indem ihr jedoch ein wenig an eurer Verpackung feilt, macht ihr das Auspacken zu einem besonderen Erlebnis.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kauft ihr zum Beispiel ein Buch, dann ist es in der Regel so eingepackt, dass ihr beim \u00d6ffnen zuerst die Vorderseite seht. Die meisten Pakete haben einen Hinweis, der euch sagt, wie ihr sie \u00f6ffnen sollt. Das kann ein Aufdruck wie \u201cHier ziehen\u201d oder eine Perforation sein. Im Inneren des Pakets haben viele Firmen die klassischen Styropor-Schnitzel durch Luftpolster ersetzt. Das reduziert M\u00fcll beim Auspacken.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">All diese Dinge ergeben zusammen das \u201cAuspack-Erlebnis\u201d eures Kunden. Hier ein paar Tipps, um sicherzustellen, dass es auch ein gutes ist:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Lasst eure Markenpers\u00f6nlichkeit durchscheinen<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn das Auspacken f\u00fcr eure Kunden bereits ein tolles Erlebnis ist, f\u00e4llt dieser Eindruck auch auf eure Marke zur\u00fcck. Hier ein paar Ideen, wie ihr euch von der Konkurrenz in braunen, gelben oder wei\u00dfen Schachteln abhebt:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Legt eine kostenlose Probe bei.<\/strong> Jeder mag es, wenn es etwas umsonst gibt. Eine kostenlose Probe bietet euren Kunden einen Zusatzwert, macht sie auf weitere Produkte aufmerksam und reduziert sogar die Wahrscheinlichkeit, dass sie ihre Bestellung zur\u00fccksenden.<\/li>\n\n\n\n<li><strong>Schickt einen Rabattcode f\u00fcr die n\u00e4chste Bestellung mit.<\/strong> Ihr wollt euch bei euren Kunden f\u00fcr ihren Einkauf bedanken und sie zu einer weiteren Bestellung anregen? Dann ist ein Rabattcode genau das Richtige! Denn damit sorgt ihr nicht nur f\u00fcr mehr Umsatz, sondern auch f\u00fcr gr\u00f6\u00dfere Kundenbindung. Auf die Karte mit eurem Rabattcode k\u00f6nnt ihr auch gleich einen QR Code drucken, damit eure Kunden eure Website sofort aufrufen k\u00f6nnen. Einen QR Code erstellt ihr ganz m\u00fchelos mit unserem <a href=\"https:\/\/www.jimdo.com\/de\/qr-code\/\">QR Code Generator<\/a>.<\/li>\n\n\n\n<li><strong>F\u00fcgt eine pers\u00f6nliche Nachricht hinzu.<\/strong> Je kleiner euer Unternehmen, desto gr\u00f6\u00dfer euer Vorteil. Eine handgeschriebene Dankeskarte kostet euch nicht viel, sorgt aber f\u00fcr eine pers\u00f6nliche und vor allem menschliche Verbindung zu euren Konten. Trudeln jeden Tag zu viele Bestellungen f\u00fcr handschriftliche Gr\u00fc\u00dfe ein, kann auch eine gedruckte und mit dem Namen personalisierte Botschaft einen gro\u00dfen Unterschied machen.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Hier ein Beispiel der britischen Sportbekleidungsmarke Apt Cavalier, die direkt von Sarah, der Gesch\u00e4ftsf\u00fchrerin, kommt:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/YV5c3NtCONK6aCUcpK5_U0XLVCy95QwGsadU812uKah1VHwmd1fth6Eo4cc6ietusjIf2DMo3BB6t8EsGuW09fEigoQQswLF_gSAgIbnaZk0iJ1p-Idt3JtIM4muAk6Vc_-8csBo\" alt=\"Die pers\u00f6nliche Gru\u00dfkarte des Onlineshops Apt Cavalier\"\/><figcaption class=\"wp-element-caption\">Eine handgeschriebene Dankeskarte von Apt Cavalier.&nbsp;<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Auf der Karte steht auch der Marken-Hashtag #BEUNSTOPPABLE zusammen mit dem Hinweis, das Produkt in euren Fotos zu taggen. Eine tolle Idee mit der ihr aus <a href=\"https:\/\/www.jimdo.com/de/magazin\/zufriedene-kunden-als-markenbotschafter\/\">euren Kunden Markenbotschafter machen k\u00f6nnt<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Vermeidet Frust<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Als das neue iPhone 6 erschien, standen die Kunden im australischen Perth stundenlang Schlange vor dem Apple Store. Als die erste Person ihr Ger\u00e4t in den H\u00e4nden hielt und die Verpackung \u00f6ffnete, fiel das Handy sofort zu Boden. Keine tolle \u201cCustomer Experience\u201d. Was war also passiert?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Weil sich die Packung nicht problemlos \u00f6ffnen lie\u00df, riss der Kunde sie mit zu viel Kraft auf, sodass das Smartphone sofort herauspurzelte. F\u00fcr Apple war dieser Vorfall eher ungew\u00f6hnlich, da man beim amerikanischen Tech-Riesen f\u00fcr gew\u00f6hnlich ganz besonders gro\u00dfen Wert auf ein tolles Auspack-Erlebnis legt. Selbst kleine Dinge wie Geruch und das Gef\u00fchl beim Abziehen der Schutzfolie werden ber\u00fccksichtigt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Doch die gute Nachricht: Als kleines Unternehmen habt ihr es leichter, mit eurer Verpackung zu experimentieren, um Frusterlebnisse wie diese zu vermeiden:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Unn\u00f6tige Verpackung \u2013 vor allem Plastik.<\/strong> Plastikm\u00fcll geh\u00f6rt zu den gr\u00f6\u00dften Problemen unserer Zeit. Millionen Tonnen davon schwimmen im Meer und in Form von Mikroplastik findet er den Weg in unsere Nahrungsmittel. Plastik zu vermeiden, wo es nur geht, ist daher immer eine tolle Idee.<\/li>\n\n\n\n<li><strong>Pakete, die sich nur schwer \u00f6ffnen lassen.<\/strong> Perforationen erleichtern das \u00d6ffnen von Kartons, ebenso wie eine aufgedruckte Anleitung. Weniger Paketband und Plastikfolie sind ebenfalls eine gute Sache.<\/li>\n\n\n\n<li><strong>Verpackungen, die beim \u00d6ffnen f\u00fcr Besch\u00e4digungen sorgen. <\/strong>Keiner will einen weiteren iPhone-6-Zwischenfall!<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Hier ein Extrembeispiel des Instagram Accounts \u201cPointless Packaging\u201d: <\/p>\n\n\n\n<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/B7HZ7JynsCw\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"13\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/B7HZ7JynsCw\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\" rel=\"noopener noreferrer\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\"> Sieh dir diesen Beitrag auf Instagram an<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/B7HZ7JynsCw\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\" rel=\"noopener noreferrer\">Ein Beitrag geteilt von Pointless Packaging (@pointless_packaging)<\/a><\/p><\/div><\/blockquote> <script async=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script>\n\n\n\n<h3 class=\"wp-block-heading\">Freude auf den ersten Blick<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Euer Paket ist endlich da! Ihr rei\u00dft das Paketband ab, \u00f6ffnet die Schachtel und endlich, da ist sie \u2026 die Rechnung. Und ein R\u00fccksendeformular. Hmmm okay. Irgendwie ern\u00fcchternd.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch wenn Papierkram das Letzte ist, was ihr in eine Schachtel legt, w\u00e4re es f\u00fcr eure Kunden wesentlich sch\u00f6ner, wenn sie ihre Bestellung als Erstes sehen. Legt Rechnungen, Anleitungen etc. also ganz unten in die Packung und euer Produkt darauf. Eine pers\u00f6nliche Gru\u00dfkarte ist hier die gro\u00dfe Ausnahme. Wenn eure Kunden ihre Ware erst einmal in den H\u00e4nden halten, ist die Wahrscheinlichkeit geringer, dass sie sie wieder zur\u00fcckgeben. Daher ist es f\u00fcr euch als Verk\u00e4ufer besser, wenn eure Kunden als Erstes ihre Bestellung zu Gesicht bekommen und nicht den Retourschein.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Eure_Verpackung_kann_mehr\"><\/span>Eure Verpackung kann mehr<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Eine gute Verpackung sch\u00fctzt eure Waren. Eine gro\u00dfartige Verpackung hilft euch bei der Kundenbindung. Diese Marketinggelegenheit solltet ihr euch nicht entgehen lassen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eure Verpackung hat auch einen gro\u00dfen Einfluss darauf, wie ihr euren Versand organisiert. Solange ein P\u00e4ckchen durch den Briefkastenschlitz passt, ist der Versand viel einfacher. Der niederl\u00e4ndische Shop <a href=\"https:\/\/www.indo-box.nl\/\">Indo-Box<\/a> verpackt seine Kuchen so clever, dass sie auch in den Briefkasten passen. Das spart Geld und hat au\u00dferdem den Vorteil, dass der Kunde bei der Lieferung nicht zu Hause sein muss.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/sOsFck7tCGowrkDsutYr9VdJHv3p2ly2YTy1vqGtkAjE2Po8XcDfcoZIt9tPn5AI3RMhHqHaT1a9npxzd6gbIfgWbyEP6NAU_J3V4T_7kECsTabvlA_D53zsO2vz4mpG1UYJ9wrf\" alt=\"Ein Foto der Kuchenverpackung des niederl\u00e4ndischen Shops Indo-Box\"\/><figcaption class=\"wp-element-caption\">Die Kuchenverpackung von Indo-Box.<\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center post-cta has-white-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8c55aac8 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h4 class=\"wp-block-heading\">Einfach online verkaufen. Mit&nbsp;Jimdo.<\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<div class=\"wp-block-group is-content-justification-right is-nowrap is-layout-flex wp-container-core-group-is-layout-f726d978 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-button\"><a data-tracking=\"post_cta_create_shop_signup\" class=\"wp-block-button__link\" href=\"https:\/\/cms.jimdo.com\/wizard\/?store=1\" target=\"_blank\" rel=\"noreferrer noopener\">Jetzt starten<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Eine gute Verpackung sch\u00fctzt eure Waren und bietet euren Kunden ein echtes Auspack-Erlebnis. Lest hier, welche am besten zu euch passt.<\/p>\n","protected":false},"author":2,"featured_media":3710,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[46],"tags":[34,29],"class_list":["post-3709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business-wissen","tag-business","tag-shop"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Praktische &amp; individuelle Verpackungen f\u00fcr Onlineshops | Jimdo<\/title>\n<meta name=\"description\" content=\"Gute Verpackungsm\u00f6glichkeiten sch\u00fctzen eure Waren und bieten ein echtes Auspackerlebnis. Lest hier, welche am besten zu euch passen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jimdo.com/de/magazin\/individuelle-verpackung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Praktische &amp; individuelle Verpackungen f\u00fcr Onlineshops | Jimdo\" \/>\n<meta property=\"og:description\" content=\"Gute Verpackungsm\u00f6glichkeiten sch\u00fctzen eure Waren und bieten ein echtes Auspackerlebnis. Lest hier, welche am besten zu euch passen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jimdo.com/de/magazin\/individuelle-verpackung\/\" \/>\n<meta property=\"og:site_name\" content=\"Das Jimdo-Magazin f\u00fcr Unternehmer\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Jimdo.de\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-25T13:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-03T08:51:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2020\/08\/jimdo-blog-featured-image-how-to-package-products-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jimdo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jimdo_de\" \/>\n<meta name=\"twitter:site\" content=\"@jimdo_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jimdo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/individuelle-verpackung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/individuelle-verpackung\\\/\"},\"author\":{\"name\":\"Jimdo\",\"@id\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/#\\\/schema\\\/person\\\/4dabebc7d5d6477941607006cb2fd592\"},\"headline\":\"Echt praktisch \u2013 So findet ihr top Verpackungsideen f\u00fcr den Onlineshop\",\"datePublished\":\"2020-08-25T13:00:00+00:00\",\"dateModified\":\"2023-08-03T08:51:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/individuelle-verpackung\\\/\"},\"wordCount\":2083,\"publisher\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/individuelle-verpackung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.jimdo.com/de/magazin\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/jimdo-blog-featured-image-how-to-package-products-3.jpg?fit=2048%2C1024&ssl=1\",\"keywords\":[\"Business-Tipps\",\"Onlineshop-Tipps\"],\"articleSection\":[\"Business-Wissen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/individuelle-verpackung\\\/\",\"url\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/individuelle-verpackung\\\/\",\"name\":\"Praktische & individuelle Verpackungen f\u00fcr Onlineshops | Jimdo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/individuelle-verpackung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/individuelle-verpackung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.jimdo.com/de/magazin\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/jimdo-blog-featured-image-how-to-package-products-3.jpg?fit=2048%2C1024&ssl=1\",\"datePublished\":\"2020-08-25T13:00:00+00:00\",\"dateModified\":\"2023-08-03T08:51:08+00:00\",\"description\":\"Gute Verpackungsm\u00f6glichkeiten sch\u00fctzen eure Waren und bieten ein echtes Auspackerlebnis. Lest hier, welche am besten zu euch passen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/individuelle-verpackung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/individuelle-verpackung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/individuelle-verpackung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.jimdo.com/de/magazin\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/jimdo-blog-featured-image-how-to-package-products-3.jpg?fit=2048%2C1024&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.jimdo.com/de/magazin\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/jimdo-blog-featured-image-how-to-package-products-3.jpg?fit=2048%2C1024&ssl=1\",\"width\":2048,\"height\":1024,\"caption\":\"Ein junger Unternehmer sucht nach der richtigen Versandverpackung\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/individuelle-verpackung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Echt praktisch \u2013 So findet ihr top Verpackungsideen f\u00fcr den Onlineshop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/\",\"name\":\"Das Jimdo-Magazin f\u00fcr Unternehmer\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/#organization\",\"name\":\"Jimdo GmbH\",\"url\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/JimdoLogo-2019-main-petrol-transparent.png\",\"contentUrl\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/JimdoLogo-2019-main-petrol-transparent.png\",\"width\":2048,\"height\":844,\"caption\":\"Jimdo GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Jimdo.de\",\"https:\\\/\\\/x.com\\\/jimdo_de\",\"https:\\\/\\\/www.instagram.com\\\/jimdo_official\\\/\",\"https:\\\/\\\/www.youtube.com\\\/jimdode\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/#\\\/schema\\\/person\\\/4dabebc7d5d6477941607006cb2fd592\",\"name\":\"Jimdo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2506bfab94e877841212e235c7148d443cd1a56b3ca7e617bd0bc48887dc682f?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2506bfab94e877841212e235c7148d443cd1a56b3ca7e617bd0bc48887dc682f?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2506bfab94e877841212e235c7148d443cd1a56b3ca7e617bd0bc48887dc682f?s=96&d=identicon&r=g\",\"caption\":\"Jimdo\"},\"description\":\"Der Blog f\u00fcr Selbstst\u00e4ndige und kleine Unternehmen rund um Selbstst\u00e4ndigkeit, Marketing und die besten Website-Tipps zu Design, Onlineshop, SEO und Co.\",\"url\":\"https:\\\/\\\/www.jimdo.com/de/magazin\\\/author\\\/jimdomagazine\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Praktische & individuelle Verpackungen f\u00fcr Onlineshops | Jimdo","description":"Gute Verpackungsm\u00f6glichkeiten sch\u00fctzen eure Waren und bieten ein echtes Auspackerlebnis. Lest hier, welche am besten zu euch passen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jimdo.com/de/magazin\/individuelle-verpackung\/","og_locale":"de_DE","og_type":"article","og_title":"Praktische & individuelle Verpackungen f\u00fcr Onlineshops | Jimdo","og_description":"Gute Verpackungsm\u00f6glichkeiten sch\u00fctzen eure Waren und bieten ein echtes Auspackerlebnis. Lest hier, welche am besten zu euch passen.","og_url":"https:\/\/www.jimdo.com/de/magazin\/individuelle-verpackung\/","og_site_name":"Das Jimdo-Magazin f\u00fcr Unternehmer","article_publisher":"https:\/\/www.facebook.com\/Jimdo.de","article_published_time":"2020-08-25T13:00:00+00:00","article_modified_time":"2023-08-03T08:51:08+00:00","og_image":[{"width":2048,"height":1024,"url":"https:\/\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2020\/08\/jimdo-blog-featured-image-how-to-package-products-3.jpg","type":"image\/jpeg"}],"author":"Jimdo","twitter_card":"summary_large_image","twitter_creator":"@jimdo_de","twitter_site":"@jimdo_de","twitter_misc":{"Verfasst von":"Jimdo","Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jimdo.com/de/magazin\/individuelle-verpackung\/#article","isPartOf":{"@id":"https:\/\/www.jimdo.com/de/magazin\/individuelle-verpackung\/"},"author":{"name":"Jimdo","@id":"https:\/\/www.jimdo.com/de/magazin\/#\/schema\/person\/4dabebc7d5d6477941607006cb2fd592"},"headline":"Echt praktisch \u2013 So findet ihr top Verpackungsideen f\u00fcr den Onlineshop","datePublished":"2020-08-25T13:00:00+00:00","dateModified":"2023-08-03T08:51:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jimdo.com/de/magazin\/individuelle-verpackung\/"},"wordCount":2083,"publisher":{"@id":"https:\/\/www.jimdo.com/de/magazin\/#organization"},"image":{"@id":"https:\/\/www.jimdo.com/de/magazin\/individuelle-verpackung\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2020\/08\/jimdo-blog-featured-image-how-to-package-products-3.jpg?fit=2048%2C1024&ssl=1","keywords":["Business-Tipps","Onlineshop-Tipps"],"articleSection":["Business-Wissen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.jimdo.com/de/magazin\/individuelle-verpackung\/","url":"https:\/\/www.jimdo.com/de/magazin\/individuelle-verpackung\/","name":"Praktische & individuelle Verpackungen f\u00fcr Onlineshops | Jimdo","isPartOf":{"@id":"https:\/\/www.jimdo.com/de/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jimdo.com/de/magazin\/individuelle-verpackung\/#primaryimage"},"image":{"@id":"https:\/\/www.jimdo.com/de/magazin\/individuelle-verpackung\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2020\/08\/jimdo-blog-featured-image-how-to-package-products-3.jpg?fit=2048%2C1024&ssl=1","datePublished":"2020-08-25T13:00:00+00:00","dateModified":"2023-08-03T08:51:08+00:00","description":"Gute Verpackungsm\u00f6glichkeiten sch\u00fctzen eure Waren und bieten ein echtes Auspackerlebnis. Lest hier, welche am besten zu euch passen.","breadcrumb":{"@id":"https:\/\/www.jimdo.com/de/magazin\/individuelle-verpackung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jimdo.com/de/magazin\/individuelle-verpackung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.jimdo.com/de/magazin\/individuelle-verpackung\/#primaryimage","url":"https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2020\/08\/jimdo-blog-featured-image-how-to-package-products-3.jpg?fit=2048%2C1024&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2020\/08\/jimdo-blog-featured-image-how-to-package-products-3.jpg?fit=2048%2C1024&ssl=1","width":2048,"height":1024,"caption":"Ein junger Unternehmer sucht nach der richtigen Versandverpackung"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jimdo.com/de/magazin\/individuelle-verpackung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.jimdo.com/de/magazin\/"},{"@type":"ListItem","position":2,"name":"Echt praktisch \u2013 So findet ihr top Verpackungsideen f\u00fcr den Onlineshop"}]},{"@type":"WebSite","@id":"https:\/\/www.jimdo.com/de/magazin\/#website","url":"https:\/\/www.jimdo.com/de/magazin\/","name":"Das Jimdo-Magazin f\u00fcr Unternehmer","description":"","publisher":{"@id":"https:\/\/www.jimdo.com/de/magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jimdo.com/de/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.jimdo.com/de/magazin\/#organization","name":"Jimdo GmbH","url":"https:\/\/www.jimdo.com/de/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.jimdo.com/de/magazin\/#\/schema\/logo\/image\/","url":"https:\/\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2020\/03\/JimdoLogo-2019-main-petrol-transparent.png","contentUrl":"https:\/\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2020\/03\/JimdoLogo-2019-main-petrol-transparent.png","width":2048,"height":844,"caption":"Jimdo GmbH"},"image":{"@id":"https:\/\/www.jimdo.com/de/magazin\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Jimdo.de","https:\/\/x.com\/jimdo_de","https:\/\/www.instagram.com\/jimdo_official\/","https:\/\/www.youtube.com\/jimdode"]},{"@type":"Person","@id":"https:\/\/www.jimdo.com/de/magazin\/#\/schema\/person\/4dabebc7d5d6477941607006cb2fd592","name":"Jimdo","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/2506bfab94e877841212e235c7148d443cd1a56b3ca7e617bd0bc48887dc682f?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2506bfab94e877841212e235c7148d443cd1a56b3ca7e617bd0bc48887dc682f?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2506bfab94e877841212e235c7148d443cd1a56b3ca7e617bd0bc48887dc682f?s=96&d=identicon&r=g","caption":"Jimdo"},"description":"Der Blog f\u00fcr Selbstst\u00e4ndige und kleine Unternehmen rund um Selbstst\u00e4ndigkeit, Marketing und die besten Website-Tipps zu Design, Onlineshop, SEO und Co.","url":"https:\/\/www.jimdo.com/de/magazin\/author\/jimdomagazine\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2020\/08\/jimdo-blog-featured-image-how-to-package-products-3.jpg?fit=2048%2C1024&ssl=1","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":6070,"url":"https:\/\/www.jimdo.com/de/magazin\/online-business-aufbauen\/","url_meta":{"origin":3709,"position":0},"title":"In 7 Schritten zu eurem eigenen Online-Business","author":"Justinas Vaiciulis","date":"18. Oktober 2024","format":false,"excerpt":"Endlich ein eigenes Online-Business aufbauen? Wir zeigen euch Schritt f\u00fcr Schritt, wie das geht \u2013 5 Tipps f\u00fcr euren Start inklusive.","rel":"","context":"In &quot;Business-Wissen&quot;","block_context":{"text":"Business-Wissen","link":"https:\/\/www.jimdo.com/de/magazin\/business-wissen\/"},"img":{"alt_text":"Drei Unternehmer*innen besprechen den Inhalt ihres Newsletters","src":"https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2021\/05\/Newsletter_01.jpg?fit=1200%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2021\/05\/Newsletter_01.jpg?fit=1200%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2021\/05\/Newsletter_01.jpg?fit=1200%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2021\/05\/Newsletter_01.jpg?fit=1200%2C600&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2021\/05\/Newsletter_01.jpg?fit=1200%2C600&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6123,"url":"https:\/\/www.jimdo.com/de/magazin\/print-on-demand-anbieter\/","url_meta":{"origin":3709,"position":1},"title":"Die 8 besten Print-on-Demand-Anbieter in Deutschland","author":"Lilli Brinkert","date":"22. November 2024","format":false,"excerpt":"Gelato, Printful, Printify & Co.: Wir stellen euch die besten Print-on-Demand-Anbieter vor. Zudem erfahrt ihr, mit welchen Tipps euer Shop erfolgreich wird.","rel":"","context":"In &quot;Business-Wissen&quot;","block_context":{"text":"Business-Wissen","link":"https:\/\/www.jimdo.com/de/magazin\/business-wissen\/"},"img":{"alt_text":"Local SEO mit Jimdo","src":"https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2019\/06\/Local-SEO-in-3-Schritten.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2019\/06\/Local-SEO-in-3-Schritten.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2019\/06\/Local-SEO-in-3-Schritten.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2019\/06\/Local-SEO-in-3-Schritten.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2019\/06\/Local-SEO-in-3-Schritten.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6526,"url":"https:\/\/www.jimdo.com/de/magazin\/was-ist-e-commerce-fulfilment-kompletter-leitfaden-fuer-2026\/","url_meta":{"origin":3709,"position":2},"title":"Was ist E-Commerce-Fulfilment? Kompletter Leitfaden f\u00fcr 2026","author":"Catherine Burmester","date":"18. Februar 2026","format":false,"excerpt":"Wichtige Erkenntnisse: E-Commerce-Fulfilment wirkt sich direkt auf die Kundenzufriedenheit, die Kundenbindung und die Skalierbarkeit des Unternehmens aus. Die Wahl des richtigen Fulfillment-Modells (intern, 3PL, Dropshipping oder Hybrid) h\u00e4ngt von der Gr\u00f6\u00dfe des Unternehmens, der Wachstumsphase und den Erwartungen der Kund*innen ab. H\u00e4ufige Fehler sind das Festhalten an nicht skalierbaren Systemen,\u2026","rel":"","context":"In &quot;Business-Wissen&quot;","block_context":{"text":"Business-Wissen","link":"https:\/\/www.jimdo.com/de/magazin\/business-wissen\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2026\/02\/image-13.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2026\/02\/image-13.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2026\/02\/image-13.jpeg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2026\/02\/image-13.jpeg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2026\/02\/image-13.jpeg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3329,"url":"https:\/\/www.jimdo.com/de/magazin\/online-verkaufen-in-5-einfachen-schritten\/","url_meta":{"origin":3709,"position":3},"title":"Online verkaufen in 5 einfachen Schritten","author":"Jimdo","date":"9. April 2020","format":false,"excerpt":"Online zu verkaufen ist f\u00fcr Selbstst\u00e4ndige und kleine Unternehmen heutzutage kein Problem. Wir zeigen euch, wie's geht!","rel":"","context":"In &quot;Website-Tipps&quot;","block_context":{"text":"Website-Tipps","link":"https:\/\/www.jimdo.com/de/magazin\/webseiten-tipps\/"},"img":{"alt_text":"Beispiel f\u00fcr einen mit Jimdo erstellten Onlineshop","src":"https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2020\/04\/Onlineshop-erstellen.jpg?fit=1200%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2020\/04\/Onlineshop-erstellen.jpg?fit=1200%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2020\/04\/Onlineshop-erstellen.jpg?fit=1200%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2020\/04\/Onlineshop-erstellen.jpg?fit=1200%2C600&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2020\/04\/Onlineshop-erstellen.jpg?fit=1200%2C600&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":5965,"url":"https:\/\/www.jimdo.com/de/magazin\/vertriebskanaele\/","url_meta":{"origin":3709,"position":4},"title":"Social Media, Website, Store: Welcher Vertriebskanal passt zu euch?","author":"Lilli Brinkert","date":"16. August 2024","format":false,"excerpt":"Es gibt viele Vertriebskan\u00e4le, \u00fcber die ihr eure Leistungen bzw. Produkte verkaufen k\u00f6nnt. Doch wie findet ihr den optimalen Vertriebskanal?","rel":"","context":"In &quot;Business-Wissen&quot;","block_context":{"text":"Business-Wissen","link":"https:\/\/www.jimdo.com/de/magazin\/business-wissen\/"},"img":{"alt_text":"Zwei Frauen arbeiten am Computer Onlineshop","src":"https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2021\/07\/jimdo-blog-onlinestores-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2021\/07\/jimdo-blog-onlinestores-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2021\/07\/jimdo-blog-onlinestores-1.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2021\/07\/jimdo-blog-onlinestores-1.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2021\/07\/jimdo-blog-onlinestores-1.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6007,"url":"https:\/\/www.jimdo.com/de/magazin\/alternativen-etsy\/","url_meta":{"origin":3709,"position":5},"title":"Geb\u00fchren, Reichweite, Verkauf: die 7 besten Alternativen zu Etsy","author":"Lilli Brinkert","date":"10. September 2024","format":false,"excerpt":"Entdeckt die besten Etsy-Alternativen f\u00fcr Kleinunternehmer*innen: Plattformen, Tipps und Vergleich.","rel":"","context":"In &quot;Inspiration&quot;","block_context":{"text":"Inspiration","link":"https:\/\/www.jimdo.com/de/magazin\/inspiration\/"},"img":{"alt_text":"Eine Modedesignerin verpackt ihre Ware","src":"https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2022\/08\/Stocksy_txpb9d46f52C7U300_Medium_646674.jpg?fit=1200%2C790&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2022\/08\/Stocksy_txpb9d46f52C7U300_Medium_646674.jpg?fit=1200%2C790&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2022\/08\/Stocksy_txpb9d46f52C7U300_Medium_646674.jpg?fit=1200%2C790&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2022\/08\/Stocksy_txpb9d46f52C7U300_Medium_646674.jpg?fit=1200%2C790&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jimdo.com/de/magazin\/wp-content\/uploads\/2022\/08\/Stocksy_txpb9d46f52C7U300_Medium_646674.jpg?fit=1200%2C790&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.jimdo.com/de/magazin\/wp-json\/wp\/v2\/posts\/3709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jimdo.com/de/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jimdo.com/de/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jimdo.com/de/magazin\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jimdo.com/de/magazin\/wp-json\/wp\/v2\/comments?post=3709"}],"version-history":[{"count":0,"href":"https:\/\/www.jimdo.com/de/magazin\/wp-json\/wp\/v2\/posts\/3709\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jimdo.com/de/magazin\/wp-json\/wp\/v2\/media\/3710"}],"wp:attachment":[{"href":"https:\/\/www.jimdo.com/de/magazin\/wp-json\/wp\/v2\/media?parent=3709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jimdo.com/de/magazin\/wp-json\/wp\/v2\/categories?post=3709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jimdo.com/de/magazin\/wp-json\/wp\/v2\/tags?post=3709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}