{"id":117,"date":"2019-08-12T10:46:52","date_gmt":"2019-08-12T10:46:52","guid":{"rendered":"http:\/\/www.jimdo.com/it/blog\/?p=117"},"modified":"2020-10-01T12:47:01","modified_gmt":"2020-10-01T10:47:01","slug":"come-competere-con-amazon","status":"publish","type":"post","link":"https:\/\/www.jimdo.com/it/blog\/come-competere-con-amazon\/","title":{"rendered":"Come il tuo business locale pu\u00f2 competere con Amazon"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le grandi catene di negozi sembrano essere dappertutto. Anche tu le nomini praticamente ogni giorno e pare impossibile competere con giganti dal brand affermato quali Nike, Microsoft, Amazon, Facebook o Ikea. Invece non \u00e8 impossibile\u2026 basta non rinnegare la propria natura di business locale e agire di conseguenza.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>In quanto piccola o media impresa (PMI) o attivit\u00e0 non avrai a disposizione lo stesso budget di Nike o Dove, ma puoi differenziarti dalle grandi aziende<\/strong>&nbsp;in termini di personalit\u00e0, originalit\u00e0, visibilit\u00e0 locale, conoscenza del prodotto e strategia pubblicitaria.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c8 proprio in questi ambiti che puoi giocare le tue carte!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sono diverse le opportunit\u00e0 di marketing che non possono essere sfruttate dalle grandi compagnie: come imprenditore o imprenditrice locale devi saperle cogliere al volo!<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Competi usando i tuoi punti di forza<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le grandi catene hanno senza dubbio i loro punti di forza. Tu puoi dire lo stesso, solo che i tuoi saranno diversi. Assicurati di essere competitivo\/a negli aspetti in cui sei gi\u00e0 pi\u00f9 forte.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ecco qua degli esempi per capire meglio cosa differenzia un brand affermato a livello globale da una piccola o media attivit\u00e0.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Grandi catene<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Punto di forza: dimensioni<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Stessa offerta in ogni negozio<\/li><li>Budget importante per il marketing<\/li><li>Capacit\u00e0 di raggiungere un ampio numero di persone (target)<\/li><li>Hanno bisogno di molti clienti per continuare a crescere<\/li><li>Servizi e prodotti generici<\/li><li>Struttura e organizzazione burocratiche<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aziende locali<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Punto di forza: unicit\u00e0<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Offerta disponibile solo nel negozio locale<\/li><li>Budget ridotto per il marketing<\/li><li>Capacit\u00e0 di raggiungere un numero limitato di persone (target)<\/li><li>Hanno bisogno di pochi clienti per continuare a crescere<\/li><li>Servizi e prodotti personalizzati<\/li><li>Struttura e organizzazione flessibili<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Come piccola azienda locale, puoi vendere prodotti e servizi che abbiano come target prima&nbsp; di tutto le persone che vivono nella tua area. Puoi inoltre permetterti di investire nella qualit\u00e0 e nella creazione di una rete che colleghi direttamente e personalmente la tua offerta ai potenziali clienti.&nbsp;<strong>Con la giusta strategia di marketing, conferirai al tuo marchio quell\u2019aura di familiarit\u00e0 che lo render\u00e0 irresistibile rispetto al brand di una multinazionale.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C&#8217;\u00e8 da dire che \u00e8 fondamentale che la tua azienda locale abbia visibilit\u00e0 su Internet. Per aiutarti a raggiungere questo obiettivo Jimdo ha sviluppato per i siti Dolphin una funzione che si chiama&nbsp;<strong><a href=\"https:\/\/www.jimdo.com/it/blog\/profilo-attivita\/\">Profilo attivit\u00e0<\/a><\/strong>:&nbsp;<strong>ti permette di inserire e aggiornare automaticamente le informazioni relative al tuo business presenti su importanti piattaforma online quali Google, Facebook e molte altre<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per i potenziali clienti sar\u00e0 molto pi\u00f9 facile trovare la tua attivit\u00e0 e il tuo sito: entrambi spiccheranno rispetto alla concorrenza.<\/p>\n\n\n<div class=\"button-iwjKgW\"><a class=\"iwjKgW\" href=\"https:\/\/account.e.jimdo.com\/it\/accounts\/signup\/\" rel=\u201dfollow\u201d target=\"_blank\">Crea il tuo sito<\/a><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">7 strategie locali per competere con le grandi catene<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Abbiamo preparato per te, piccola media azienda o libero\/a professionista, una lista di 7 strategie di marketing a livello locale. Ogni suggerimento ti aiuter\u00e0 a posizionarti meglio sul mercato e ti render\u00e0 pi\u00f9 forte in campi nei quali le grandi catene sono deboli.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. Racconta il tuo prodotto o servizio locale con una storia unica<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Il successo di Amazon e di altri giganti del commercio globale risiede nella produzione\/vendita tempestiva su larga scala di prodotti generici:<\/strong>&nbsp;chiunque pu\u00f2 comprarli in qualsiasi posto si trovi.&nbsp;<strong>La competitivit\u00e0 di una compagnia locale si gioca invece sull\u2019unicit\u00e0 dei prodotti\/servizi.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ogni supermercato vende pane, per\u00f2 solitamente la selezione di pane \u00e8 sempre la stessa in tutte le filiali. Se gestisci un panificio locale puoi fare molto meglio! Utilizza materie prime prodotte nella tua zona e segui ricette regionali per fare il pane. Potresti addirittura organizzare una collaborazione col museo di storia locale e offrire in loco una degustazione di pane che veniva consumato nella tua regione nel Medioevo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se vendi vestiti sportivi per bambini, puoi includere nella tua offerta ed esporre vestiti prodotti da aziende locali.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se guidi un taxi, puoi prediligere le strade pi\u00f9 importanti della citt\u00e0 o del paese e usare la tua conoscenza del posto per far scendere i clienti nel punto pi\u00f9 interessante per loro e pi\u00f9 conveniente per te. Ricordati di menzionare tutti questi dettagli e peculiarit\u00e0 della tua offerta&nbsp;<a href=\"https:\/\/www.jimdo.com/it/blog\/come-scrivere-descrizioni-prodotti\/\">nelle descrizioni dei prodotti e servizi presenti sul tuo sito<\/a>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Perch\u00e9 questa strategia dovrebbe funzionare?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I beni e servizi prodotti in larga scala sono utili, ma spesso sono anonimi, difettano di personalit\u00e0.&nbsp;<strong>Offrendo un prodotto o un&nbsp; servizio locale e quindi peculiare dai ai clienti una ragione in pi\u00f9 per sceglierti.<\/strong>&nbsp;Questo focus sull\u2019originalit\u00e0 del prodotto o servizio, messo in risalto attraverso una storia che esalti la localit\u00e0 e che faccia presa sulla comunit\u00e0, \u00e8 un aspetto che non potr\u00e0 MAI essere copiato da una multinazionale.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Qualsiasi supermercato vende miele. In alcuni supermercati ad Amburgo, in Germania, i e le clienti possono trovare del miele prodotto nella regione circostante. Per sottolineare ancora di pi\u00f9 la provenienza locale del miele, l\u2019apicoltore ha etichettato ogni variet\u00e0 indicandola col nome dell\u2019area specifica in cui le api raccolgono i pollini e producono il nettare.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Fai riferimento a eventi locali<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gli ampi margini di profitto delle grandi compagnie dipendono dal fatto che esse si servono di processi di produzione e di strategie di marketing standard, applicabili dappertutto.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Magari sponsorizzano un evento come il Super Bowl oppure organizzano una campagna pubblicitaria legata a una festa nazionale, ma non avranno mai idea di cosa succede in una specifica regione, ad esempio non sponsorizzeranno mai una maratona locale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tu puoi farlo!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ti forniamo qualche esempio chiarificatore:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Sono nati due panda nello zoo cittadino. Per celebrare il lieto evento, promuovi nella tua panetteria i biscotti glassati con cioccolato nero e bianco con un\u2019offerta \u201cPrendi 2 paghi 1\u201d<\/li><li>Dopo una lunga ristrutturazione, finalmente la piscina comunale ha riaperto i battenti. Organizza una campagna pubblicitaria e dai risalto sul tuo sito al fatto che vendi costumi da bagno per bambini<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Riesci a immaginare Amazon che sfrutta queste opportunit\u00e0? Non sa neanche che ci sono per cui non \u00e8 nella posizione di agire di conseguenza. Tu puoi!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Perch\u00e9 questa strategia dovrebbe funzionare?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quello che succede a livello locale influenza direttamente la vita delle persone che risiedono nella tua area. Inserisciti in questa dinamica e&nbsp;<strong>connetti il tuo business alle novit\u00e0 o offri una soluzione a un problema o bisogno della comunit\u00e0 del luogo.<\/strong>&nbsp;In questo modo farai parlare di te e darai l\u2019impressione di essere un attore importante nella vita della comunit\u00e0 locale.<br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. Offri un\u2019esperienza unica<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Un altro punto debole di un\u2019azienda di grandi dimensioni \u00e8 il livello di competenza del servizio clienti.&nbsp;<strong>La maggior parte dei dipendenti che lavorano nelle grandi catene sono assunti per vendere dei prodotti, ma non hanno la minima idea di come essi vengano realizzati.<\/strong>&nbsp;I commessi possono affettare del pane per te, ma difficilmente sapranno come si svolge il processo di produzione. Tu, che gestisci la panetteria locale di cui parlavamo prima, lo sai e puoi spiegare tutto nei minimi dettagli!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puoi chiarire con precisione quali farine hai usato e puoi consigliare dei tipi di pane speciali a chi soffre di intolleranze o allergie. Potresti addirittura organizzare workshop e aprire il tuo laboratorio alle visite, anche quelle di bambini durante il periodo delle vacanze estive, grandi e piccini adoreranno l\u2019iniziativa!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se invece, mantenendo gli esempi citati prima, possiedi un negozio di abbigliamento per bambini, puoi organizzare una giornata dedicata interamente alla prova dei capi della nuova collezione. Si tratta di un evento che difficilmente sar\u00e0 organizzato da una multinazionale e pubblicizzato sul suo sito perch\u00e9 il rischio di affrontare costi eccessivi in caso di resi sarebbe troppo elevato.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Perch\u00e9 questa strategia dovrebbe funzionare?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tua presenza fisica, la tua competenza, insomma&nbsp;<strong>il \u201ccapitale umano\u201d aggiungono valore al bene o servizio che offri e quindi spingono i e le potenziali clienti a scegliere te piuttosto che il prodotto generico e privo di personalit\u00e0 di una multinazionale.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L\u2019unicit\u00e0 dell\u2019offerta<\/strong>&nbsp;inoltre fa parlare di te, ti rende riconoscibile,&nbsp;<strong>\u00e8 parte di una storia che merita di essere raccontata.<\/strong>&nbsp;Chiunque pu\u00f2 comprare una qualsiasi farina in un supermercato, ma se una persona va al mulino del paese vicino, racconter\u00e0 l\u2019esperienza che ha vissuto e a casa cuocer\u00e0 al forno un pane dal sapore unico.<br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4. Diventa familiare ai clienti<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Quante volte ti \u00e8 capitato di vedere Bill Gates<\/strong>&nbsp;nel negozio dove hai comprato gli ultimi PC?&nbsp;<strong>Mark Zuckerberg, Jeff Bezos o Tim Cook?<\/strong>&nbsp;Ti hanno mai chiamato per chiederti se fossi contento\/a dei loro prodotti o servizi? Molto probabilmente non ti capiter\u00e0 mai nella vita di incontrarli o parlare con loro.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Se possiedi un\u2019azienda locale, hai la grande opportunit\u00e0 di diventare un viso familiare per i e le potenziali clienti e di creare una connessione reale con loro.<\/strong>&nbsp;Mostra il lato umano del tuo business: parla con le persone interessate ai tuoi prodotti e servizi, offri loro un bicchiere di acqua fresca durante una giornata afosa, chiedi se il pane cotto seguendo la ricetta che hai loro consigliato era buono o no. Nessuna di queste azioni \u00e8 particolarmente dispendiosa in termini di tempo, denaro e impegno, ma comunica alla clientela quel calore e quell\u2019umanit\u00e0 che nessuna multinazionale pu\u00f2 offrire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Perch\u00e9 questa strategia dovrebbe funzionare?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La maggior parte delle persone ama sentirsi connessa ad altre persone, ma questo contatto umano non piove dal cielo, si costruisce. Parla con la gente e non dare l\u2019impressione che la conversazione sia finalizzata solo alla vendita: mostra un interesse sincero per i bisogni dei e delle potenziali clienti.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questo approccio porta un beneficio inaspettato. Non rientrer\u00e0 nei profitti contabilizzati in partita doppia, ma \u00e8 infinitamente prezioso: la gentilezza che mostri torner\u00e0 indietro e ci\u00f2 render\u00e0 la tua vita e quegli degli altri molto pi\u00f9 piena.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">5.&nbsp;Usa parole chiave locali sul tuo sito<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il sito della tua panetteria a Napoli non deve comparire tra i risultati di ricerca di chi scrive su Google \u201cpanetteria\u201d e magari si trova ad Agrigento.&nbsp;<strong>Google deve capire dove si trova la tua attivit\u00e0 e tu puoi aiutarlo in questo, in modo che dia la priorit\u00e0 al tuo business locale<\/strong>&nbsp;e lo mostri a chi si trova nella tua zona e sta effettivamente cercando il tipo di prodotto o servizio che offri.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pensa alle parole che potenziali clienti potrebbero usare per trovarti. Se la tua attivit\u00e0 si trova in una grande citt\u00e0, sarebbe meglio indicare il quartiere, oppure direttamente l\u2019indirizzo esatto (\u201cpanetteria al Vomero\u201d \u00e8 molto pi\u00f9 preciso di \u201cpanetteria a Napoli\u201d).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le grandi compagnie non usano di solito questa strategia perch\u00e9 non vogliono essere collegate a una specifica area geografica.<\/strong>&nbsp;L\u2019algoritmo di Google le mostra solo nel caso ci sia un ufficio o una filiale nella citt\u00e0, ma in ogni caso non includeranno nel loro sito delle parole chiave per ogni singola regione in cui sono presenti.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il lavoro di ricerca di parole chiave fa parte della tua&nbsp;<strong><a href=\"https:\/\/www.jimdo.com/it/blog\/local-seo\/\">strategia SEO a livello locale<\/a><\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Perch\u00e9 questa strategia dovrebbe funzionare?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le parole chiave locali ti rendono visibile alle persone che stanno cercando il prodotto o servizio che offri proprio nella zona in cui si trova la tua attivit\u00e0. \u00c8 importante che il tuo sito faccia subito capire loro il valore della tua offerta. Inoltre per avere ancora pi\u00f9 visibilit\u00e0, puoi usare la nostra funzione&nbsp;<a href=\"https:\/\/www.jimdo.com/it/blog\/profilo-attivita\/\"><strong>Profilo attivit\u00e0<\/strong>&nbsp;<\/a>in modo che Google (ma anche tante altre importanti piattaforme) mostrino esattamente dove ti trovi, gli orari di apertura e tante altre importanti informazioni.<\/p>\n\n\n<div class=\"button-iwjKgW\"><a class=\"iwjKgW\" href=\"https:\/\/account.e.jimdo.com\/it\/accounts\/signup\/\" rel=\u201dfollow\u201d target=\"_blank\">Crea il tuo sito<\/a><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">6. Ricorri alla pubblicit\u00e0 locale<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nella zona o regione in cui ha sede il tuo business c\u2019\u00e8 un quotidiano o una stazione TV\/radio locale?&nbsp;<strong>Le grandi aziende<\/strong>&nbsp;tendono a voler raggiungere il maggior numero di persone possibile col minimo dispendio di risorse, quindi&nbsp;<strong>di solito non investono in pubblicit\u00e0 locale perch\u00e9 raggiungerebbero un target troppo limitato per i loro standard.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ancora una volta puoi sfruttare a tuo favore questo aspetto:&nbsp;<strong>la pubblicit\u00e0 locale si rivolge a un audience che coincide con la tua clientela ideale<\/strong>&nbsp;perch\u00e9 pi\u00f9 vicina e, visto che la domanda di pubblicit\u00e0 non \u00e8 alta perch\u00e9 mancano i concorrenti pi\u00f9 grandi e danarosi, i costi sono ragionevoli e alla tua portata.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Importante! Puoi comprare degli spazi pubblicitari sul sito di quotidiani\/TV locali oppure&nbsp;<strong>puoi provare&nbsp;<a href=\"https:\/\/www.jimdo.com/it/blog\/aumentare-traffico-con-facebook-ads\/\">Facebook Ads<\/a><\/strong>: a seconda dell\u2019area scelta, con una spesa di 25 euro puoi raggiungere migliaia e migliaia di persone nella tua zona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Perch\u00e9 questa strategia dovrebbe funzionare?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gli annunci pubblicitari possono essere impostati su specifici target. Fondamentalmente scegli tu le persone che vuoi raggiungere. Anche in questo ambito la concorrenza \u00e8 ridotta perch\u00e9 le multinazionali solitamente non sono interessate a target locali, bens\u00ec internazionali. A te non interessa che la tua pubblicit\u00e0 appaia agli spettatori della Champion League: lascia che Nike o Adidas spendano i loro soldi l\u00ec e usa i tuoi per gli annunci locali.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">7. Sponsorizza eventi o squadre sportive locali<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La sponsorizzazione \u00e8 un ottimo modo per dare visibilit\u00e0 alla tua impresa e presentarla a una potenziale clientela.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pensa a un torneo locale di calcio per bambini e immagina le frotte di genitori urlanti e orgogliosi che comporta. Vuoi che non siano disposti a pagare fiori di quattrini per vedere i loro bimbi con l\u2019abbigliamento sportivo pi\u00f9 bello e nuovo fiammante?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La vera competizione non avviene in campo, bens\u00ec tra gli spalti!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se hai un negozio di abbigliamento per bambini, si tratta di una ghiotta occasione per farti pubblicit\u00e0. Gli organizzatori dell\u2019evento saranno contenti del tuo contributo e tu attirerai l\u2019attenzione del tuo target ideale di consumatori.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Figurati se l\u2019Adidas investir\u00e0 in un evento cos\u00ec piccolo! Non sarebbe efficiente e remunerativo per loro avere a che fare con centinaia o migliaia di organizzatori.&nbsp;<strong>Per una piccola compagnia invece il ritorno economico ci sarebbe anche solo sponsorizzando 3 o 4 eventi locali all\u2019anno.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ecco qua qualche esempio di eventi locali a cui puoi contribuire:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Metti a disposizione i locali della tua azienda per una sagra (es.: la sagra del pane di Osilo)<\/li><li>Piazza il palco per il concerto di una band cittadina<\/li><li>Hai una gastronomia? Organizza e prepara il catering (vegano) per il congresso organizzato da un\u2019associazione locale per la tutela degli animali<\/li><li>Sei un fioraio? Regala regolarmente dei bei fiori freschi al negozio di sartoria per matrimoni pi\u00f9 conosciuto in citt\u00e0&nbsp;<\/li><li>Hai un negozio di abbigliamento sportivo? Sponsorizza un torneo di calcio locale<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Come puoi vedere dagli esempi,&nbsp;<strong>la sponsorizzazione non implica necessariamente l\u2019investimento di denaro.<\/strong>&nbsp;In molti casi il tuo tempo, l\u2019impegno, i tuoi prodotti o servizi saranno gi\u00e0 abbastanza.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Perch\u00e9 questa strategia dovrebbe funzionare?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sponsorizzare un evento locale connette la tua impresa ai valori, agli interessi e alle esigenze delle persone che partecipano all\u2019evento. Ti aiuta a influenzare il modo in cui potenziali clienti vedono la tua azienda, il tuo brand. Insomma \u00e8 una strategia perfetta per raggiungere un mix di vecchi e nuovi clienti e per rafforzare la fama del tuo marchio.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le multinazionali non scompariranno. Mai.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Questo non significa che la loro esistenza far\u00e0 scomparire piccole aziende come la tua.<\/strong>&nbsp;Abbiamo visto che ci sono miliardi di opportunit\u00e0 per avere successo non nonostante tu possieda una piccola media impresa, bens\u00ec proprio perch\u00e9 il tuo business \u00e8 locale.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00ec addio alle paure o ai complessi di inferiorit\u00e0: in quanto piccola media impresa offri qualcosa di unico. Non hai bisogno di agire come Amazon, se non sei Amazon. Piuttosto&nbsp;<strong>abbraccia e asseconda la natura locale del tuo business e falla diventare la chiave del tuo successo.&nbsp;<\/strong><\/p>\n\n\n<div class=\"button-iwjKgW\"><a class=\"iwjKgW\" href=\"https:\/\/account.e.jimdo.com\/it\/accounts\/signup\/\" rel=\u201dfollow\u201d target=\"_blank\">Crea il tuo sito<\/a><\/div>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center post-cta is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading\">Scegli Jimdo per creare il sito per la tua attivit\u00e0.<\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<div class=\"wp-block-button\"><a data-tracking=\"post_cta_create_website_signup\" class=\"wp-block-button__link\" href=\"https:\/\/cms.jimdo.com\/wizard\/\">Inizia ora<\/a><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>7 strategie suggerite alle piccole medie imprese (PMI) per un business locale di successo che competa con le grandi multinazionali.<\/p>\n","protected":false},"author":2,"featured_media":118,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[27,23,26],"class_list":["post-117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business","tag-marketing","tag-pmi","tag-shop"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>7 strategie per un business locale che competa con Amazon - Jimdo<\/title>\n<meta name=\"description\" content=\"7 strategie suggerite alle piccole medie imprese (PMI) per un business locale di successo che competa con le grandi multinazionali.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jimdo.com/it/blog\/come-competere-con-amazon\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"7 strategie per un business locale che competa con Amazon - Jimdo\" \/>\n<meta property=\"og:description\" content=\"7 strategie suggerite alle piccole medie imprese (PMI) per un business locale di successo che competa con le grandi multinazionali.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jimdo.com/it/blog\/come-competere-con-amazon\/\" \/>\n<meta property=\"og:site_name\" content=\"Jimdo Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Jimdo.Italia\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-12T10:46:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-01T10:47:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/fai-competere-la-tua-attivita\u0300-locale-con-amazon.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jimdo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Jimdo_Italia\" \/>\n<meta name=\"twitter:site\" content=\"@Jimdo_Italia\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jimdo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/come-competere-con-amazon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/come-competere-con-amazon\\\/\"},\"author\":{\"name\":\"Jimdo\",\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/#\\\/schema\\\/person\\\/496021aff53df88753916a127e412586\"},\"headline\":\"Come il tuo business locale pu\u00f2 competere con Amazon\",\"datePublished\":\"2019-08-12T10:46:52+00:00\",\"dateModified\":\"2020-10-01T10:47:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/come-competere-con-amazon\\\/\"},\"wordCount\":2647,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/come-competere-con-amazon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.jimdo.com/it/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/fai-competere-la-tua-attivita%CC%80-locale-con-amazon.jpg?fit=1400%2C700&ssl=1\",\"keywords\":[\"Marketing\",\"PMI\",\"Shop\"],\"articleSection\":[\"Consigli per il business\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.jimdo.com/it/blog\\\/come-competere-con-amazon\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/come-competere-con-amazon\\\/\",\"url\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/come-competere-con-amazon\\\/\",\"name\":\"7 strategie per un business locale che competa con Amazon - Jimdo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/come-competere-con-amazon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/come-competere-con-amazon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.jimdo.com/it/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/fai-competere-la-tua-attivita%CC%80-locale-con-amazon.jpg?fit=1400%2C700&ssl=1\",\"datePublished\":\"2019-08-12T10:46:52+00:00\",\"dateModified\":\"2020-10-01T10:47:01+00:00\",\"description\":\"7 strategie suggerite alle piccole medie imprese (PMI) per un business locale di successo che competa con le grandi multinazionali.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jimdo.com/it/blog\\\/come-competere-con-amazon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/come-competere-con-amazon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.jimdo.com/it/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/fai-competere-la-tua-attivita%CC%80-locale-con-amazon.jpg?fit=1400%2C700&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.jimdo.com/it/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/fai-competere-la-tua-attivita%CC%80-locale-con-amazon.jpg?fit=1400%2C700&ssl=1\",\"width\":1400,\"height\":700,\"caption\":\"fai-competere-la-tua-attivita\u0300-locale-con-amazon\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/\",\"name\":\"Jimdo Blog Italy\",\"description\":\"Consigli di marketing e web per piccole imprese e freelance\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/#organization\",\"name\":\"Jimdo GmbH\",\"url\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Jimdo-Logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Jimdo-Logo@2x.png\",\"width\":200,\"height\":75,\"caption\":\"Jimdo GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Jimdo.Italia\\\/\",\"https:\\\/\\\/x.com\\\/Jimdo_Italia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/#\\\/schema\\\/person\\\/496021aff53df88753916a127e412586\",\"name\":\"Jimdo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2506bfab94e877841212e235c7148d443cd1a56b3ca7e617bd0bc48887dc682f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2506bfab94e877841212e235c7148d443cd1a56b3ca7e617bd0bc48887dc682f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2506bfab94e877841212e235c7148d443cd1a56b3ca7e617bd0bc48887dc682f?s=96&d=mm&r=g\",\"caption\":\"Jimdo\"},\"description\":\"Il blog di Jimdo \u00e8 dedicato a tutti gli imprenditori, alle imprenditrici, ai\\\/alle freelance che si impegnano per realizzare con passione la propria idea e il proprio progetto. Qui troverai informazioni su start-up, business online di successo, storie di persone che hanno scelto Jimdo per portare online la propria attivit\u00e0 e anche tanti consigli per il tuo sito, il tuo shop online, dritte SEO e tanto altro.\",\"sameAs\":[\"http:\\\/\\\/www.jimdo.com/it/blog\"],\"url\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/author\\\/jimdoblogit\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"7 strategie per un business locale che competa con Amazon - Jimdo","description":"7 strategie suggerite alle piccole medie imprese (PMI) per un business locale di successo che competa con le grandi multinazionali.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jimdo.com/it/blog\/come-competere-con-amazon\/","og_locale":"it_IT","og_type":"article","og_title":"7 strategie per un business locale che competa con Amazon - Jimdo","og_description":"7 strategie suggerite alle piccole medie imprese (PMI) per un business locale di successo che competa con le grandi multinazionali.","og_url":"https:\/\/www.jimdo.com/it/blog\/come-competere-con-amazon\/","og_site_name":"Jimdo Blog","article_publisher":"https:\/\/www.facebook.com\/Jimdo.Italia\/","article_published_time":"2019-08-12T10:46:52+00:00","article_modified_time":"2020-10-01T10:47:01+00:00","og_image":[{"width":1400,"height":700,"url":"https:\/\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/fai-competere-la-tua-attivita\u0300-locale-con-amazon.jpg","type":"image\/jpeg"}],"author":"Jimdo","twitter_card":"summary_large_image","twitter_creator":"@Jimdo_Italia","twitter_site":"@Jimdo_Italia","twitter_misc":{"Scritto da":"Jimdo","Tempo di lettura stimato":"13 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jimdo.com/it/blog\/come-competere-con-amazon\/#article","isPartOf":{"@id":"https:\/\/www.jimdo.com/it/blog\/come-competere-con-amazon\/"},"author":{"name":"Jimdo","@id":"https:\/\/www.jimdo.com/it/blog\/#\/schema\/person\/496021aff53df88753916a127e412586"},"headline":"Come il tuo business locale pu\u00f2 competere con Amazon","datePublished":"2019-08-12T10:46:52+00:00","dateModified":"2020-10-01T10:47:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jimdo.com/it/blog\/come-competere-con-amazon\/"},"wordCount":2647,"commentCount":0,"publisher":{"@id":"https:\/\/www.jimdo.com/it/blog\/#organization"},"image":{"@id":"https:\/\/www.jimdo.com/it/blog\/come-competere-con-amazon\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/fai-competere-la-tua-attivita%CC%80-locale-con-amazon.jpg?fit=1400%2C700&ssl=1","keywords":["Marketing","PMI","Shop"],"articleSection":["Consigli per il business"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jimdo.com/it/blog\/come-competere-con-amazon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jimdo.com/it/blog\/come-competere-con-amazon\/","url":"https:\/\/www.jimdo.com/it/blog\/come-competere-con-amazon\/","name":"7 strategie per un business locale che competa con Amazon - Jimdo","isPartOf":{"@id":"https:\/\/www.jimdo.com/it/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jimdo.com/it/blog\/come-competere-con-amazon\/#primaryimage"},"image":{"@id":"https:\/\/www.jimdo.com/it/blog\/come-competere-con-amazon\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/fai-competere-la-tua-attivita%CC%80-locale-con-amazon.jpg?fit=1400%2C700&ssl=1","datePublished":"2019-08-12T10:46:52+00:00","dateModified":"2020-10-01T10:47:01+00:00","description":"7 strategie suggerite alle piccole medie imprese (PMI) per un business locale di successo che competa con le grandi multinazionali.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jimdo.com/it/blog\/come-competere-con-amazon\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.jimdo.com/it/blog\/come-competere-con-amazon\/#primaryimage","url":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/fai-competere-la-tua-attivita%CC%80-locale-con-amazon.jpg?fit=1400%2C700&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/fai-competere-la-tua-attivita%CC%80-locale-con-amazon.jpg?fit=1400%2C700&ssl=1","width":1400,"height":700,"caption":"fai-competere-la-tua-attivita\u0300-locale-con-amazon"},{"@type":"WebSite","@id":"https:\/\/www.jimdo.com/it/blog\/#website","url":"https:\/\/www.jimdo.com/it/blog\/","name":"Jimdo Blog Italy","description":"Consigli di marketing e web per piccole imprese e freelance","publisher":{"@id":"https:\/\/www.jimdo.com/it/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jimdo.com/it/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.jimdo.com/it/blog\/#organization","name":"Jimdo GmbH","url":"https:\/\/www.jimdo.com/it/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.jimdo.com/it/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.jimdo.com/it/blog\/wp-content\/uploads\/2021\/03\/Jimdo-Logo@2x.png","contentUrl":"https:\/\/www.jimdo.com/it/blog\/wp-content\/uploads\/2021\/03\/Jimdo-Logo@2x.png","width":200,"height":75,"caption":"Jimdo GmbH"},"image":{"@id":"https:\/\/www.jimdo.com/it/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Jimdo.Italia\/","https:\/\/x.com\/Jimdo_Italia"]},{"@type":"Person","@id":"https:\/\/www.jimdo.com/it/blog\/#\/schema\/person\/496021aff53df88753916a127e412586","name":"Jimdo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2506bfab94e877841212e235c7148d443cd1a56b3ca7e617bd0bc48887dc682f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2506bfab94e877841212e235c7148d443cd1a56b3ca7e617bd0bc48887dc682f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2506bfab94e877841212e235c7148d443cd1a56b3ca7e617bd0bc48887dc682f?s=96&d=mm&r=g","caption":"Jimdo"},"description":"Il blog di Jimdo \u00e8 dedicato a tutti gli imprenditori, alle imprenditrici, ai\/alle freelance che si impegnano per realizzare con passione la propria idea e il proprio progetto. Qui troverai informazioni su start-up, business online di successo, storie di persone che hanno scelto Jimdo per portare online la propria attivit\u00e0 e anche tanti consigli per il tuo sito, il tuo shop online, dritte SEO e tanto altro.","sameAs":["http:\/\/www.jimdo.com/it/blog"],"url":"https:\/\/www.jimdo.com/it/blog\/author\/jimdoblogit\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/fai-competere-la-tua-attivita%CC%80-locale-con-amazon.jpg?fit=1400%2C700&ssl=1","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":435,"url":"https:\/\/www.jimdo.com/it/blog\/promuovere-pmi-senza-spendere\/","url_meta":{"origin":117,"position":0},"title":"Promuovi la tua PMI senza spendere nulla","author":"Jimdo","date":"20 Gennaio 2020","format":false,"excerpt":"Per promuovere il tuo business, non devi essere un mago del marketing o disporre di un grande budget. Ecco 8 modi per farlo a costo zero!","rel":"","context":"In &quot;Consigli per il business&quot;","block_context":{"text":"Consigli per il business","link":"https:\/\/www.jimdo.com/it/blog\/business\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/09\/promuovere-pmi-senza-spendere.jpg?fit=699%2C352&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/09\/promuovere-pmi-senza-spendere.jpg?fit=699%2C352&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/09\/promuovere-pmi-senza-spendere.jpg?fit=699%2C352&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":240,"url":"https:\/\/www.jimdo.com/it/blog\/come-supportare-pmi\/","url_meta":{"origin":117,"position":1},"title":"Come la tua attivit\u00e0 pu\u00f2 supportare altre PMI in crisi","author":"Jimdo","date":"30 Marzo 2020","format":false,"excerpt":"Come imprenditore o libero professionista puoi usare la tua attivit\u00e0 per aiutare altre PMI durante l\u2019emergenza coronavirus. Scopri come fare, contribuisci con idee e passa parola!","rel":"","context":"In &quot;Consigli per il business&quot;","block_context":{"text":"Consigli per il business","link":"https:\/\/www.jimdo.com/it/blog\/business\/"},"img":{"alt_text":"usa-la-tua-attivita\u0300-per-supportare-pmi-e-liberi-professionisti-in-crisi-per-il-corona-virus","src":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/usa-la-tua-attivita%CC%80-per-supportare-pmi-e-liberi-professionisti-in-crisi-per-il-corona-virus.jpg?fit=698%2C349&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/usa-la-tua-attivita%CC%80-per-supportare-pmi-e-liberi-professionisti-in-crisi-per-il-corona-virus.jpg?fit=698%2C349&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/usa-la-tua-attivita%CC%80-per-supportare-pmi-e-liberi-professionisti-in-crisi-per-il-corona-virus.jpg?fit=698%2C349&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":158,"url":"https:\/\/www.jimdo.com/it/blog\/come-valutare-idea-di-business\/","url_meta":{"origin":117,"position":2},"title":"Come valutare la tua idea","author":"Jimdo","date":"6 Febbraio 2019","format":false,"excerpt":"Hai un'idea per una nuova attivit\u00e0? Avviarne una non \u00e8 semplice, scopri come puoi fare per valutare la tua idea prima di investire i tuoi risparmi!","rel":"","context":"In &quot;Consigli per il business&quot;","block_context":{"text":"Consigli per il business","link":"https:\/\/www.jimdo.com/it/blog\/business\/"},"img":{"alt_text":"idee-e-valutazione-della-tua-attivita\u0300-e-commerce","src":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/idee-e-valutazione-della-tua-attivita%CC%80-e-commerce.jpg?fit=700%2C350&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/idee-e-valutazione-della-tua-attivita%CC%80-e-commerce.jpg?fit=700%2C350&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/idee-e-valutazione-della-tua-attivita%CC%80-e-commerce.jpg?fit=700%2C350&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/idee-e-valutazione-della-tua-attivita%CC%80-e-commerce.jpg?fit=700%2C350&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":127,"url":"https:\/\/www.jimdo.com/it/blog\/local-seo\/","url_meta":{"origin":117,"position":3},"title":"Local SEO: ottimizzare sito per la ricerca locale su Google in 3 passi","author":"Jimdo","date":"24 Giugno 2019","format":false,"excerpt":"Le persone cercano spesso prodotti\/servizi da acquistare nelle vicinanze. Con la Local SEO aumenti la visibilit\u00e0 su Google della tua attivit\u00e0 locale.","rel":"","context":"In &quot;Consigli per il sito&quot;","block_context":{"text":"Consigli per il sito","link":"https:\/\/www.jimdo.com/it/blog\/sito-web\/"},"img":{"alt_text":"local-seo-per-migliorare-la-visibilita\u0300-e-il-posizionamento-su-google-del-sito-della-tua-attivita\u0300-locale","src":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/local-seo-per-migliorare-la-visibilita%CC%80-e-il-posizionamento-su-google-del-sito-della-tua-attivita%CC%80-locale.jpg?fit=1200%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/local-seo-per-migliorare-la-visibilita%CC%80-e-il-posizionamento-su-google-del-sito-della-tua-attivita%CC%80-locale.jpg?fit=1200%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/local-seo-per-migliorare-la-visibilita%CC%80-e-il-posizionamento-su-google-del-sito-della-tua-attivita%CC%80-locale.jpg?fit=1200%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/local-seo-per-migliorare-la-visibilita%CC%80-e-il-posizionamento-su-google-del-sito-della-tua-attivita%CC%80-locale.jpg?fit=1200%2C600&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/local-seo-per-migliorare-la-visibilita%CC%80-e-il-posizionamento-su-google-del-sito-della-tua-attivita%CC%80-locale.jpg?fit=1200%2C600&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":815,"url":"https:\/\/www.jimdo.com/it/blog\/crowdfunding-pmi\/","url_meta":{"origin":117,"position":4},"title":"Le 6 migliori piattaforme di crowdfunding per le PMI","author":"Jimdo","date":"15 Luglio 2021","format":false,"excerpt":"Cos\u2019\u00e8 il crowdfunding? Pu\u00f2 servirti per finanziare la tua piccola attivit\u00e0? Quale piattaforma di crowdfunding \u00e8 adatta a te? Leggi i nostri consigli e suggerimenti.","rel":"","context":"In &quot;Consigli per il business&quot;","block_context":{"text":"Consigli per il business","link":"https:\/\/www.jimdo.com/it/blog\/business\/"},"img":{"alt_text":"piattaforme crowdfunding per PMI","src":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2021\/07\/crowdfunding-blog-header.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2021\/07\/crowdfunding-blog-header.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2021\/07\/crowdfunding-blog-header.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2021\/07\/crowdfunding-blog-header.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2021\/07\/crowdfunding-blog-header.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":236,"url":"https:\/\/www.jimdo.com/it/blog\/supporto-pmi-durante-coronavirus\/","url_meta":{"origin":117,"position":5},"title":"Sostegno alle PMI ai tempi del coronavirus","author":"Jimdo","date":"18 Marzo 2020","format":false,"excerpt":"Piccole e medie imprese sono colpite duramente dall\u2019emergenza. Come consumatore\/consumatrice puoi aiutarle: ecco delle idee per farlo. Aggiungi pure i tuoi consigli!","rel":"","context":"In &quot;Consigli per il business&quot;","block_context":{"text":"Consigli per il business","link":"https:\/\/www.jimdo.com/it/blog\/business\/"},"img":{"alt_text":"sostengo-alle-piccole-medie-imprese-per-l-emergenza-coronavirus","src":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/sostengo-alle-piccole-medie-imprese-per-l-emergenza-coronavirus.jpg?fit=698%2C349&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/sostengo-alle-piccole-medie-imprese-per-l-emergenza-coronavirus.jpg?fit=698%2C349&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/sostengo-alle-piccole-medie-imprese-per-l-emergenza-coronavirus.jpg?fit=698%2C349&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.jimdo.com/it/blog\/wp-json\/wp\/v2\/posts\/117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jimdo.com/it/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jimdo.com/it/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jimdo.com/it/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jimdo.com/it/blog\/wp-json\/wp\/v2\/comments?post=117"}],"version-history":[{"count":0,"href":"https:\/\/www.jimdo.com/it/blog\/wp-json\/wp\/v2\/posts\/117\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jimdo.com/it/blog\/wp-json\/wp\/v2\/media\/118"}],"wp:attachment":[{"href":"https:\/\/www.jimdo.com/it/blog\/wp-json\/wp\/v2\/media?parent=117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jimdo.com/it/blog\/wp-json\/wp\/v2\/categories?post=117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jimdo.com/it/blog\/wp-json\/wp\/v2\/tags?post=117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}