{"id":181,"date":"2019-03-25T10:06:22","date_gmt":"2019-03-25T10:06:22","guid":{"rendered":"http:\/\/www.jimdo.com/it/blog\/?p=181"},"modified":"2020-10-23T11:38:13","modified_gmt":"2020-10-23T09:38:13","slug":"come-scrivere-descrizioni-prodotti","status":"publish","type":"post","link":"https:\/\/www.jimdo.com/it/blog\/come-scrivere-descrizioni-prodotti\/","title":{"rendered":"6 consigli per scrivere ottime descrizioni dei tuoi prodotti"},"content":{"rendered":"\n<p>Al giorno d\u2019oggi occorrono pochi minuti per creare uno shop virtuale: basta settare le impostazioni, aggiungere delle foto e si \u00e8 pronti per vendere online. Descrivere i prodotti in modo cos\u00ec convincente da spingere le persone a comprarli, richiede invece un po\u2019 pi\u00f9 d\u2019impegno. &nbsp;&nbsp;<\/p>\n\n\n\n<p>Come descriveresti un prodotto a un\/a potenziale cliente? Quali informazioni non possono mancare nelle pagine dello shop e come convincere i visitatori a cliccare sul bottone \u201cAggiungi al carrello\u201d?<\/p>\n\n\n\n<p>In questo articolo ti dar\u00f2 dei suggerimenti su come presentare i prodotti e ti mostrer\u00f2 alcuni esempi. La descrizione degli articoli richiede creativit\u00e0, ma questo non vuol dire che tu debba essere&nbsp;<a href=\"https:\/\/it.wikipedia.org\/wiki\/Don_Draper\" target=\"_blank\" rel=\"noreferrer noopener\">Don Draper<\/a>! &nbsp;Seguendo queste semplici regole, imparerai a scrivere descrizioni informative, autentiche, convincenti e, ultimo ma non meno importante, ottimizzate per i motori di ricerca:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Pensa alle domande che potrebbe fare un\/a potenziale acquirente<\/li><li>Specifica sempre i dettagli: dimensioni, colori, materiali, etc.<\/li><li>Racconta la storia del prodotto sottolineando la sua unicit\u00e0<\/li><li>Assicurati che i testi siano facili e veloci da leggere<\/li><li>Aggiungi le recensioni di clienti soddisfatti\/e<\/li><li>Ottimizza le descrizioni da un punto di vista SEO<\/li><\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">1) Anticipa le domande della clientela<\/h2>\n\n\n\n<p>Ogni volta che qualcuno compra un articolo sul tuo shop online, sta compiendo un atto di fiducia: non pu\u00f2 vedere davvero il prodotto, non pu\u00f2 tenerlo tra le mani e nemmeno provarlo. \u00c8 proprio per questo motivo che le descrizioni del prodotto sono cos\u00ec importanti.<\/p>\n\n\n\n<p>Se proprio non sai cosa scrivere, immagina le possibili domande di un\/a potenziale cliente. Ad esempio, come veste l\u2019abito? Come mi starebbe? Dov\u2019\u00e8 stato confezionato? Perch\u00e9 costa cos\u00ec tanto?<\/p>\n\n\n\n<p>Come affermato dal guru del marketing Neil Patel: &#8220;Se dopo aver letto la descrizione che hai fatto di un prodotto hai ancora delle domande, allora non hai fatto un buon lavoro.&#8221;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/image.jimcdn.com\/app\/cms\/image\/transf\/dimension%3D700x10000%3Aformat%3Dpng\/path\/s11684123ec8ecd7d\/image\/i935756a036a20300\/version\/1553504844\/esempio-di-una-buona-descrizione-di-un-mascara.png?ssl=1\" alt=\"Esempio di una buona descrizione di un mascara \"\/><\/figure>\n\n\n\n<p>Individuando e rispondendo alle domande giuste, del tipo &#8220;Questi pantaloni si restringeranno nella lavatrice?&#8221; oppure &#8220;Riuscir\u00f2 a staccare dal barattolo quell\u2019etichetta che non mi piace?&#8221;, dimostri anche di capire quali sono le esigenze dei\/delle clienti.<\/p>\n\n\n\n<p>Osserva la descrizione del mascara Dior tratta dal sito di Douglas:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/image.jimcdn.com\/app\/cms\/image\/transf\/dimension%3D700x10000%3Aformat%3Dpng\/path\/s11684123ec8ecd7d\/image\/i4efff21a580d7407\/version\/1553504980\/una-descrizione-del-prodotto-che-indica-tutti-i-dettagli-utili-al-alla-cliente.png?ssl=1\" alt=\"Una descrizione del prodotto che indica tutti i dettagli utili al\/alla cliente\"\/><\/figure>\n\n\n\n<p>Questa descrizione chiarisce immediatamente la particolarit\u00e0 del mascara rispetto ad altri prodotti di questo tipo e risponde a diverse domande del\/la cliente quali: \u201c\u00c8 davvero caro, perch\u00e9 dovrei scegliere questo mascara piuttosto che un altro?\u201d oppure \u201cNon sar\u00e0 troppo compatto all\u2019interno e quindi difficile da applicare sulle ciglia?\u201d.<\/p>\n\n\n\n<p>La descrizione infatti ci dice che \u201c<em>Dior reinventa il volume con Diorshow Pump \u2019N\u2019 Volume, un mascara inedito della Maison, per ciglia XXL<\/em>\u201d e \u201c<em>Spettacolare sotto ogni punto di vista, questo nuovo mascara Dior rivoluziona il gesto volumizzante. Premendo semplicemente il tubetto flessibile del mascara, la formula ultra-volumizzante si fluidifica e l&#8217;applicatore si carica di prodotto cremoso. Ottieni subito un volume estremo!<\/em>\u201d. &nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2) Descrivi sempre tutti i dettagli dei prodotti<\/h2>\n\n\n\n<p>Avrai sentito dire spesso che quando si scrive un testo per il web \u00e8 meglio limitare il numero delle parole perch\u00e9 le persone di solito non amano leggere testi lunghi sui siti. \u00c8 tutto vero, ma devi comunque specificare tutti i dettagli dei tuoi prodotti perch\u00e9 solo cos\u00ec un\/a cliente potr\u00e0 capire cosa sta comprando esattamente ed eviterai in futuro resi e richieste di rimborso da parte di persone che hanno comprato per sbaglio un tuo articolo.<\/p>\n\n\n\n<p>Indica sempre le dimensioni o la taglia, il peso, il colore, i materiali, la provenienza dell\u2019oggetto e cos\u00ec via.<\/p>\n\n\n\n<p>Nell\u2019esempio mostrato sopra, vengono forniti dettagli precisi non solo sul prodotto stesso (ultra-volumizzante, fluido e cremoso), ma anche sui materiali del tubetto (flessibile) e dell\u2019applicatore (con bacchetta rigida e setole morbide), a dimostrazione del fatto che nulla deve essere lasciato al caso, nemmeno quando si tratta di acquistare un semplice mascara.<\/p>\n\n\n\n<p>Dopotutto non vale proprio la pena prendere in giro un\/a cliente, spingedolo\/a a comprare qualcosa che non corrisponde alle sue aspettative o esigenze.<\/p>\n\n\n\n<p>Una descrizione che indica tutte le caratteristiche di un articolo, inoltre, \u00e8 indice di profonda conoscenza del prodotto e di attenzione verso i dettagli, aspetti che ti permetteranno di guadagnarti la&nbsp;fiducia&nbsp;delle persone.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">3) Distinguiti dalla concorrenza<\/h2>\n\n\n\n<p>\u00c8 molto probabile che il tuo articolo (o qualcosa di simile) sia gi\u00e0 disponibile, a un prezzo inferiore, presso un grande rivenditore online. La fortuna delle PMI (piccole medie imprese) sta nel fatto che le motivazioni che spingono consumatori e consumatrici a comprare un oggetto piuttosto che un altro, non sono solo il prezzo e la convenienza.<\/p>\n\n\n\n<p>Ad esempio, guarda&nbsp;<a href=\"https:\/\/www.imprentas.eu\/it\/formaggi-sardi\/194-pecorino-riserva-nera-8055519930005.html\" target=\"_blank\" rel=\"noreferrer noopener\">questa descrizione<\/a>&nbsp;del Pecorino sardo Riserva Nera, prodotto appunto in Sardegna:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/image.jimcdn.com\/app\/cms\/image\/transf\/dimension%3D446x10000%3Aformat%3Dpng\/path\/s11684123ec8ecd7d\/image\/iea67fcd483ea2dbf\/version\/1553505481\/esempio-di-un-ottima-descrizione-di-un-formaggio-prodotto-in-sardegna.png?ssl=1\" alt=\"Esempio di un\u2019ottima descrizione di un formaggio prodotto in Sardegna \"\/><\/figure>\n\n\n\n<p>Saresti in grado di trovare presso un grande rivenditore un formaggio altrettanto buono e che costa meno? Puoi scommetterci.<\/p>\n\n\n\n<p>Chi ha scritto la descrizione vuole per\u00f2 farti capire perch\u00e9 dovresti acquistare proprio questo pecorino. Innanzitutto ti racconta che tale prodotto \u00e8 famoso in tutto il mondo e viene fatto solo in Sardegna con materie prime locali di eccezionale qualit\u00e0. Il testo inoltre ti assicura che gusterai qualcosa di davvero speciale e non reperibile facilmente altrove.<\/p>\n\n\n\n<p>Riesci gi\u00e0 a immaginare la delizia e la particolarit\u00e0 di questo pecorino, vero?<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/image.jimcdn.com\/app\/cms\/image\/transf\/dimension%3D700x10000%3Aformat%3Dpng\/path\/s11684123ec8ecd7d\/image\/i83ce8ebbcb76d7cc\/version\/1553505617\/descrizione-del-pecorino-sardo-riserva-nera.png?ssl=1\" alt=\"Descrizione del Pecorino Sardo Riserva Nera\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">4) Scrivi descrizioni di qualit\u00e0, facili e veloci da leggere<\/h2>\n\n\n\n<p>La formattazione dei testi che pubblichi sul sito deve sempre essere adattata&nbsp;<a href=\"https:\/\/www.jimdo.com/it/blog\/scrivere-contenuti-per-sito-o-shop\/\">al web e al tipo di lettura<\/a>&nbsp;dei visitatori dello shop.<\/p>\n\n\n\n<p>Titoli, elenchi puntati, paragrafi brevi, immagini a volont\u00e0: ecco come puoi semplificare la vita e soprattutto lo shopping dei\/delle potenziali clienti.<\/p>\n\n\n\n<p>Forse avrai sentito dire che \u00e8 meglio usare parole ad effetto o abbondare col superlativo, ma io ti consiglio di ricorrere a un linguaggio naturale, quello che userebbe una persona normale che non cerca per forza di attirare l\u2019attenzione.<\/p>\n\n\n\n<p>La descrizione del succhietto prodotto da MAM forse mi aiuter\u00e0 a chiarire meglio quello che intendo: &nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/image.jimcdn.com\/app\/cms\/image\/transf\/dimension%3D700x10000%3Aformat%3Dpng\/path\/s11684123ec8ecd7d\/image\/i15e7a4386456de0e\/version\/1553505779\/un-esempio-di-descrizione-del-prodotto-facile-e-veloce-da-leggere.png?ssl=1\" alt=\"Un esempio di descrizione del prodotto facile e veloce da leggere \"\/><\/figure>\n\n\n\n<p>Basta un\u2019immagine e un elenco puntato capace di toccare i punti giusti per spiegarti perch\u00e8 si tratta di un prodotto speciale. Innanzitutto, quale genitore con parecchie ore di sonno arretrate non spenderebbe 10,45 \u20ac (forse eccessivi per un ciuccio) per non dover alzarsi nel cuore della notte per cercare il succhietto del proprio bambino? Il succhietto che si illumina potrebbe essere la soluzione giusta! Inoltre, questa breve descrizione punta su un altro aspetto molto caro ai genitori, ovvero la qualit\u00e0 dei materiali e la sicurezza di un prodotto sicuro e testato.<\/p>\n\n\n\n<p>Come bilanciare l\u2019esigenza di raccontare la particolarit\u00e0 di un oggetto con il bisogno di scrivere una descrizione concisa? Scrivi un&nbsp;<strong>breve paragrafo sulla storia dell\u2019articolo o un titolo esemplificativo (come nel caso del succhietto) e descrivine le caratteristiche in un elenco puntato<\/strong>.<\/p>\n\n\n\n<p>In questo modo accontenterai sia le persone che vogliono rendersi subito conto di cosa si tratta che quelle curiose di conoscere i dettagli.<\/p>\n\n\n\n<p>Ti serve qualche dritta su come scattare le foto ai tuoi prodotti?<\/p>\n\n\n\n<p>Dai uno sguardo al nostro articolo \u201c<a href=\"https:\/\/www.jimdo.com/it/blog\/come-costruire-un-light-box\/\">Costruisci un light box per fotografare e presentare al meglio i tuoi prodotti<\/a>\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">5) Aggiungi le testimonianze di clienti soddisfatti<\/h2>\n\n\n\n<p>Un altro elemento molto importante che dovrebbe essere sempre presente nelle descrizioni dei prodotti \u00e8 la valutazione di clienti soddisfatti\/e: vero e proprio riconoscimento sociale, prova pubblica del valore di quello che vendi. Pu\u00f2 trattarsi di una recensione, di una testimonianza o di un link che rimanda a un articolo di giornale\/blog che parla dei tuoi prodotti.<\/p>\n\n\n\n<p>Per quale motivo i consumatori danno peso a quello che dicono degli estranei? Perch\u00e9 volente o nolente la dichiarazione di una persona soddisfatta costituisce un potentissimo incentivo all\u2019acquisto. Pensaci bene\u2026 prima di fidarti di chi vende dei prodotti online, vuoi sapere se altri clienti prima di te si sono trovati bene.<\/p>\n\n\n\n<p>Secondo un recente sondaggio di&nbsp;<a href=\"https:\/\/www.brightlocal.com\/learn\/local-consumer-review-survey\/\" target=\"_blank\" rel=\"noreferrer noopener\">BrightLocal<\/a>, gli\/le acquirenti leggono almeno 10 recensioni prima di acquistare un prodotto online.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">6) Ottimizza le descrizioni in un\u2019ottica SEO<\/h2>\n\n\n\n<p>Non sono solo i\/le potenziali clienti a leggere le recensioni: anche i motori di ricerca lo fanno. Ecco perch\u00e9 devi sempre tenere a mente la SEO quando descrivi i tuoi prodotti, altrimenti non compariranno mai su Google.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Usa delle parole chiave per dare un nome ai tuoi prodotti:<\/strong>&nbsp;chiarisci sempre di che oggetto si tratta e lascia perdere giochi di parole e nomi che ti sembrano \u201cirresistibili\u201d. Il nome del primo prodotto che abbiamo mostrato \u00e8 un buon esempio perch\u00e9 contiene la parola \u201cmascara\u201d. &nbsp;<\/li><li><strong>Aggiungi qualche parola chiave nella descrizione<\/strong>&nbsp;assicurandoti che le parole scelte risultino naturali nel contesto, non \u201cforzate\u201d. La descrizione deve essere fluida e accattivante, ma sempre informativa: se vendi formaggio la descrizione dovr\u00e0 contenere la parola \u201cformaggio\u201d. &nbsp;<\/li><li><strong>Non copiare e incollare le descrizioni di prodotti che trovi su altri siti<\/strong>&nbsp;perch\u00e9 Google non le riconoscer\u00e0 come interessanti o originali e i tuoi testi scompariranno dai risultati di ricerca, scavalcati dai siti che hanno gi\u00e0 un buon posizionamento. &nbsp;<\/li><\/ul>\n\n\n\n<p><strong>Nota bene<\/strong>: ricordati sempre di inserire gli alt text per le immagini, di creare nello shop una navigazione e una struttura chiara e intuitiva. Questi e&nbsp;<a href=\"https:\/\/www.jimdo.com\/blog\/improving-online-stores-seo-and-sales\/\" target=\"_blank\" rel=\"noreferrer noopener\">altri accorgimenti SEO<\/a>&nbsp;miglioreranno il rendimento del tuo shop online. Fortunatamente nei siti creati con Jimdo&nbsp;<a href=\"https:\/\/www.jimdo.com/it/blog\/funzioni-seo-automatiche\/\">molte funzioni SEO sono gi\u00e0 automatizzate<\/a>.<\/p>\n\n\n\n<p><strong>Conclusione:<\/strong><\/p>\n\n\n\n<p>\u00c8 vero che in rete si possono trovare tantissimi generatori automatici di descrizioni, ma perch\u00e9 accontentarti di qualcosa di raffazzonato e generico quando puoi scrivere dei testi unici, originali e persuasivi?<\/p>\n\n\n\n<p>Spero davvero che questo articolo ti abbia convinto di quanto sia facile descrivere efficacemente i tuoi prodotti e soprattutto di quanto sia meglio farlo con parole tue.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center post-cta is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h4 class=\"wp-block-heading\">Scegli Jimdo per vendere online.<\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<div class=\"wp-block-button\"><a data-tracking=\"post_cta_create_shop_signup\" class=\"wp-block-button__link\" href=\"https:\/\/cms.jimdo.com\/wizard\/?store=1\">Inizia ora<\/a><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Esempi efficaci e 6 semplici regole da seguire per imparare a descrivere i prodotti che vendi online.<\/p>\n","protected":false},"author":2,"featured_media":502,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[27,26],"class_list":["post-181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sito-web","tag-marketing","tag-shop"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>6 consigli per scrivere ottime descrizioni di prodotti - Jimdo<\/title>\n<meta name=\"description\" content=\"Esempi efficaci e 6 semplici regole da seguire per imparare a descrivere i prodotti che vendi online.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jimdo.com/it/blog\/come-scrivere-descrizioni-prodotti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"6 consigli per scrivere ottime descrizioni di prodotti - Jimdo\" \/>\n<meta property=\"og:description\" content=\"Esempi efficaci e 6 semplici regole da seguire per imparare a descrivere i prodotti che vendi online.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jimdo.com/it/blog\/come-scrivere-descrizioni-prodotti\/\" \/>\n<meta property=\"og:site_name\" content=\"Jimdo Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Jimdo.Italia\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-25T10:06:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-23T09:38:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jimdo.com/it/blog\/wp-content\/uploads\/2019\/03\/come-scrivere-descrizioni-prodotti.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1026\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jimdo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Jimdo_Italia\" \/>\n<meta name=\"twitter:site\" content=\"@Jimdo_Italia\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jimdo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/come-scrivere-descrizioni-prodotti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/come-scrivere-descrizioni-prodotti\\\/\"},\"author\":{\"name\":\"Jimdo\",\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/#\\\/schema\\\/person\\\/496021aff53df88753916a127e412586\"},\"headline\":\"6 consigli per scrivere ottime descrizioni dei tuoi prodotti\",\"datePublished\":\"2019-03-25T10:06:22+00:00\",\"dateModified\":\"2020-10-23T09:38:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/come-scrivere-descrizioni-prodotti\\\/\"},\"wordCount\":1567,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/come-scrivere-descrizioni-prodotti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.jimdo.com/it/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/come-scrivere-descrizioni-prodotti.jpg?fit=2048%2C1026&ssl=1\",\"keywords\":[\"Marketing\",\"Shop\"],\"articleSection\":[\"Consigli per il sito\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.jimdo.com/it/blog\\\/come-scrivere-descrizioni-prodotti\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/come-scrivere-descrizioni-prodotti\\\/\",\"url\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/come-scrivere-descrizioni-prodotti\\\/\",\"name\":\"6 consigli per scrivere ottime descrizioni di prodotti - Jimdo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/come-scrivere-descrizioni-prodotti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/come-scrivere-descrizioni-prodotti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.jimdo.com/it/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/come-scrivere-descrizioni-prodotti.jpg?fit=2048%2C1026&ssl=1\",\"datePublished\":\"2019-03-25T10:06:22+00:00\",\"dateModified\":\"2020-10-23T09:38:13+00:00\",\"description\":\"Esempi efficaci e 6 semplici regole da seguire per imparare a descrivere i prodotti che vendi online.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jimdo.com/it/blog\\\/come-scrivere-descrizioni-prodotti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/come-scrivere-descrizioni-prodotti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.jimdo.com/it/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/come-scrivere-descrizioni-prodotti.jpg?fit=2048%2C1026&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.jimdo.com/it/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/come-scrivere-descrizioni-prodotti.jpg?fit=2048%2C1026&ssl=1\",\"width\":2048,\"height\":1026},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/\",\"name\":\"Jimdo Blog Italy\",\"description\":\"Consigli di marketing e web per piccole imprese e freelance\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/#organization\",\"name\":\"Jimdo GmbH\",\"url\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Jimdo-Logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Jimdo-Logo@2x.png\",\"width\":200,\"height\":75,\"caption\":\"Jimdo GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Jimdo.Italia\\\/\",\"https:\\\/\\\/x.com\\\/Jimdo_Italia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/#\\\/schema\\\/person\\\/496021aff53df88753916a127e412586\",\"name\":\"Jimdo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2506bfab94e877841212e235c7148d443cd1a56b3ca7e617bd0bc48887dc682f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2506bfab94e877841212e235c7148d443cd1a56b3ca7e617bd0bc48887dc682f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2506bfab94e877841212e235c7148d443cd1a56b3ca7e617bd0bc48887dc682f?s=96&d=mm&r=g\",\"caption\":\"Jimdo\"},\"description\":\"Il blog di Jimdo \u00e8 dedicato a tutti gli imprenditori, alle imprenditrici, ai\\\/alle freelance che si impegnano per realizzare con passione la propria idea e il proprio progetto. Qui troverai informazioni su start-up, business online di successo, storie di persone che hanno scelto Jimdo per portare online la propria attivit\u00e0 e anche tanti consigli per il tuo sito, il tuo shop online, dritte SEO e tanto altro.\",\"sameAs\":[\"http:\\\/\\\/www.jimdo.com/it/blog\"],\"url\":\"https:\\\/\\\/www.jimdo.com/it/blog\\\/author\\\/jimdoblogit\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"6 consigli per scrivere ottime descrizioni di prodotti - Jimdo","description":"Esempi efficaci e 6 semplici regole da seguire per imparare a descrivere i prodotti che vendi online.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jimdo.com/it/blog\/come-scrivere-descrizioni-prodotti\/","og_locale":"it_IT","og_type":"article","og_title":"6 consigli per scrivere ottime descrizioni di prodotti - Jimdo","og_description":"Esempi efficaci e 6 semplici regole da seguire per imparare a descrivere i prodotti che vendi online.","og_url":"https:\/\/www.jimdo.com/it/blog\/come-scrivere-descrizioni-prodotti\/","og_site_name":"Jimdo Blog","article_publisher":"https:\/\/www.facebook.com\/Jimdo.Italia\/","article_published_time":"2019-03-25T10:06:22+00:00","article_modified_time":"2020-10-23T09:38:13+00:00","og_image":[{"width":2048,"height":1026,"url":"https:\/\/www.jimdo.com/it/blog\/wp-content\/uploads\/2019\/03\/come-scrivere-descrizioni-prodotti.jpg","type":"image\/jpeg"}],"author":"Jimdo","twitter_card":"summary_large_image","twitter_creator":"@Jimdo_Italia","twitter_site":"@Jimdo_Italia","twitter_misc":{"Scritto da":"Jimdo","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jimdo.com/it/blog\/come-scrivere-descrizioni-prodotti\/#article","isPartOf":{"@id":"https:\/\/www.jimdo.com/it/blog\/come-scrivere-descrizioni-prodotti\/"},"author":{"name":"Jimdo","@id":"https:\/\/www.jimdo.com/it/blog\/#\/schema\/person\/496021aff53df88753916a127e412586"},"headline":"6 consigli per scrivere ottime descrizioni dei tuoi prodotti","datePublished":"2019-03-25T10:06:22+00:00","dateModified":"2020-10-23T09:38:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jimdo.com/it/blog\/come-scrivere-descrizioni-prodotti\/"},"wordCount":1567,"commentCount":0,"publisher":{"@id":"https:\/\/www.jimdo.com/it/blog\/#organization"},"image":{"@id":"https:\/\/www.jimdo.com/it/blog\/come-scrivere-descrizioni-prodotti\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2019\/03\/come-scrivere-descrizioni-prodotti.jpg?fit=2048%2C1026&ssl=1","keywords":["Marketing","Shop"],"articleSection":["Consigli per il sito"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jimdo.com/it/blog\/come-scrivere-descrizioni-prodotti\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jimdo.com/it/blog\/come-scrivere-descrizioni-prodotti\/","url":"https:\/\/www.jimdo.com/it/blog\/come-scrivere-descrizioni-prodotti\/","name":"6 consigli per scrivere ottime descrizioni di prodotti - Jimdo","isPartOf":{"@id":"https:\/\/www.jimdo.com/it/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jimdo.com/it/blog\/come-scrivere-descrizioni-prodotti\/#primaryimage"},"image":{"@id":"https:\/\/www.jimdo.com/it/blog\/come-scrivere-descrizioni-prodotti\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2019\/03\/come-scrivere-descrizioni-prodotti.jpg?fit=2048%2C1026&ssl=1","datePublished":"2019-03-25T10:06:22+00:00","dateModified":"2020-10-23T09:38:13+00:00","description":"Esempi efficaci e 6 semplici regole da seguire per imparare a descrivere i prodotti che vendi online.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jimdo.com/it/blog\/come-scrivere-descrizioni-prodotti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.jimdo.com/it/blog\/come-scrivere-descrizioni-prodotti\/#primaryimage","url":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2019\/03\/come-scrivere-descrizioni-prodotti.jpg?fit=2048%2C1026&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2019\/03\/come-scrivere-descrizioni-prodotti.jpg?fit=2048%2C1026&ssl=1","width":2048,"height":1026},{"@type":"WebSite","@id":"https:\/\/www.jimdo.com/it/blog\/#website","url":"https:\/\/www.jimdo.com/it/blog\/","name":"Jimdo Blog Italy","description":"Consigli di marketing e web per piccole imprese e freelance","publisher":{"@id":"https:\/\/www.jimdo.com/it/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jimdo.com/it/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.jimdo.com/it/blog\/#organization","name":"Jimdo GmbH","url":"https:\/\/www.jimdo.com/it/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.jimdo.com/it/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.jimdo.com/it/blog\/wp-content\/uploads\/2021\/03\/Jimdo-Logo@2x.png","contentUrl":"https:\/\/www.jimdo.com/it/blog\/wp-content\/uploads\/2021\/03\/Jimdo-Logo@2x.png","width":200,"height":75,"caption":"Jimdo GmbH"},"image":{"@id":"https:\/\/www.jimdo.com/it/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Jimdo.Italia\/","https:\/\/x.com\/Jimdo_Italia"]},{"@type":"Person","@id":"https:\/\/www.jimdo.com/it/blog\/#\/schema\/person\/496021aff53df88753916a127e412586","name":"Jimdo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2506bfab94e877841212e235c7148d443cd1a56b3ca7e617bd0bc48887dc682f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2506bfab94e877841212e235c7148d443cd1a56b3ca7e617bd0bc48887dc682f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2506bfab94e877841212e235c7148d443cd1a56b3ca7e617bd0bc48887dc682f?s=96&d=mm&r=g","caption":"Jimdo"},"description":"Il blog di Jimdo \u00e8 dedicato a tutti gli imprenditori, alle imprenditrici, ai\/alle freelance che si impegnano per realizzare con passione la propria idea e il proprio progetto. Qui troverai informazioni su start-up, business online di successo, storie di persone che hanno scelto Jimdo per portare online la propria attivit\u00e0 e anche tanti consigli per il tuo sito, il tuo shop online, dritte SEO e tanto altro.","sameAs":["http:\/\/www.jimdo.com/it/blog"],"url":"https:\/\/www.jimdo.com/it/blog\/author\/jimdoblogit\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2019\/03\/come-scrivere-descrizioni-prodotti.jpg?fit=2048%2C1026&ssl=1","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":246,"url":"https:\/\/www.jimdo.com/it/blog\/come-vendere-facilmente-online\/","url_meta":{"origin":181,"position":0},"title":"Inizia a vendere online in 5 semplici passi","author":"Jimdo","date":"16 Aprile 2020","format":false,"excerpt":"Mantieni viva la tua attivit\u00e0 creando uno shop online che ti permetta di guadagnare anche in questo periodo difficile.","rel":"","context":"In &quot;Consigli per il business&quot;","block_context":{"text":"Consigli per il business","link":"https:\/\/www.jimdo.com/it/blog\/business\/"},"img":{"alt_text":"inizia-a-vendere-online-in-5-semplici-passi-jimdo","src":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/inizia-a-vendere-online-in-5-semplici-passi-jimdo.jpg?fit=699%2C350&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/inizia-a-vendere-online-in-5-semplici-passi-jimdo.jpg?fit=699%2C350&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/inizia-a-vendere-online-in-5-semplici-passi-jimdo.jpg?fit=699%2C350&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":156,"url":"https:\/\/www.jimdo.com/it/blog\/shop-per-vendere-online\/","url_meta":{"origin":181,"position":1},"title":"Vuoi vendere online? Puoi farlo con Jimdo!","author":"Jimdo","date":"13 Febbraio 2019","format":false,"excerpt":"Creare uno shop online non \u00e8 mai stato cos\u00ec semplice. Basta caricare la foto del prodotto, aggiungere una descrizione e il gioco \u00e8 fatto! Inizia ora!","rel":"","context":"In &quot;Consigli per il business&quot;","block_context":{"text":"Consigli per il business","link":"https:\/\/www.jimdo.com/it/blog\/business\/"},"img":{"alt_text":"puoi-vendere-online-con-jimdo-dolphin","src":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/puoi-vendere-online-con-jimdo-dolphin.jpg?fit=700%2C350&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/puoi-vendere-online-con-jimdo-dolphin.jpg?fit=700%2C350&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/puoi-vendere-online-con-jimdo-dolphin.jpg?fit=700%2C350&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/puoi-vendere-online-con-jimdo-dolphin.jpg?fit=700%2C350&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":781,"url":"https:\/\/www.jimdo.com/it/blog\/strategia-marketing-online-shop\/","url_meta":{"origin":181,"position":2},"title":"Strategia marketing online in 5 passi per il tuo shop","author":"Jimdo","date":"14 Giugno 2021","format":false,"excerpt":"Aumentare le vendite online non deve essere difficile. Segui questi 5 passi per definire e potenziare la strategia di marketing per il tuo shop online.","rel":"","context":"In &quot;Consigli per il business&quot;","block_context":{"text":"Consigli per il business","link":"https:\/\/www.jimdo.com/it/blog\/business\/"},"img":{"alt_text":"Strategia marketing online per lo shop","src":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2021\/06\/OnlineMarketingStrategy.jpeg?fit=714%2C357&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2021\/06\/OnlineMarketingStrategy.jpeg?fit=714%2C357&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2021\/06\/OnlineMarketingStrategy.jpeg?fit=714%2C357&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2021\/06\/OnlineMarketingStrategy.jpeg?fit=714%2C357&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":213,"url":"https:\/\/www.jimdo.com/it/blog\/come-ridurre-resi-sullo-shop\/","url_meta":{"origin":181,"position":3},"title":"Come ridurre i resi sul tuo shop online","author":"Jimdo","date":"22 Luglio 2020","format":false,"excerpt":"Riduci la percentuale di resi sul tuo shop online e i relativi costi a tuo carico seguendo cinque semplici consigli.","rel":"","context":"In &quot;Consigli per il sito&quot;","block_context":{"text":"Consigli per il sito","link":"https:\/\/www.jimdo.com/it/blog\/sito-web\/"},"img":{"alt_text":"Come ridurre i resi sul tuo shop online","src":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/Come-ridurre-i-resi-sul-tuo-shop-online.jpg?fit=1200%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/Come-ridurre-i-resi-sul-tuo-shop-online.jpg?fit=1200%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/Come-ridurre-i-resi-sul-tuo-shop-online.jpg?fit=1200%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/Come-ridurre-i-resi-sul-tuo-shop-online.jpg?fit=1200%2C600&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/Come-ridurre-i-resi-sul-tuo-shop-online.jpg?fit=1200%2C600&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":224,"url":"https:\/\/www.jimdo.com/it/blog\/motivi-abbandono-shop\/","url_meta":{"origin":181,"position":4},"title":"7 motivi per cui i clienti lasciano il tuo shop","author":"Jimdo","date":"26 Luglio 2018","format":false,"excerpt":"Capisci perch\u00e9 i tuoi clienti abbandonano lo shop. Ti elenchiamo 7 motivi pi\u00f9 qualche dritta per trasformare i tuoi visitatori in clienti soddisfatti.","rel":"","context":"In &quot;Consigli per il business&quot;","block_context":{"text":"Consigli per il business","link":"https:\/\/www.jimdo.com/it/blog\/business\/"},"img":{"alt_text":"7-motivi-per-cui-i-clienti-lasciano-il-tuo-shop","src":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/sette-motivi-per-cui-i-clienti-lasciano-il-tuo-shop.jpg?fit=698%2C349&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/sette-motivi-per-cui-i-clienti-lasciano-il-tuo-shop.jpg?fit=698%2C349&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2020\/07\/sette-motivi-per-cui-i-clienti-lasciano-il-tuo-shop.jpg?fit=698%2C349&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":565,"url":"https:\/\/www.jimdo.com/it/blog\/vendere-sui-social-e-convertire-follower-in-clienti\/","url_meta":{"origin":181,"position":5},"title":"Vendere sui social: ora \u00e8 ancora pi\u00f9 facile","author":"Jimdo","date":"26 Gennaio 2021","format":false,"excerpt":"Promuovi, mostra e vendi anche su Facebook e Instagram i prodotti inseriti nel tuo shop Jimdo.","rel":"","context":"In &quot;Consigli per il business&quot;","block_context":{"text":"Consigli per il business","link":"https:\/\/www.jimdo.com/it/blog\/business\/"},"img":{"alt_text":"Vendere su Instagram & Facebook","src":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2021\/01\/Blog-Header-V2-714x357-1.jpeg?fit=714%2C357&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2021\/01\/Blog-Header-V2-714x357-1.jpeg?fit=714%2C357&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2021\/01\/Blog-Header-V2-714x357-1.jpeg?fit=714%2C357&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jimdo.com/it/blog\/wp-content\/uploads\/2021\/01\/Blog-Header-V2-714x357-1.jpeg?fit=714%2C357&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.jimdo.com/it/blog\/wp-json\/wp\/v2\/posts\/181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jimdo.com/it/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jimdo.com/it/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jimdo.com/it/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jimdo.com/it/blog\/wp-json\/wp\/v2\/comments?post=181"}],"version-history":[{"count":0,"href":"https:\/\/www.jimdo.com/it/blog\/wp-json\/wp\/v2\/posts\/181\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jimdo.com/it/blog\/wp-json\/wp\/v2\/media\/502"}],"wp:attachment":[{"href":"https:\/\/www.jimdo.com/it/blog\/wp-json\/wp\/v2\/media?parent=181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jimdo.com/it/blog\/wp-json\/wp\/v2\/categories?post=181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jimdo.com/it/blog\/wp-json\/wp\/v2\/tags?post=181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}